{"id":1171387,"date":"2020-09-25T14:02:50","date_gmt":"2020-09-25T18:02:50","guid":{"rendered":""},"modified":"2024-05-06T12:25:01","modified_gmt":"2024-05-06T16:25:01","slug":"a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19","status":"publish","type":"questions","link":"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/","title":{"rendered":"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19?"},"content":{"rendered":"<div class=\"info-box view2\">Vous pourriez \u00eatre admissible aux prestations de maladie de l&#8217;assurance-emploi pendant que vous \u00eates en cong\u00e9 sp\u00e9cial en raison d&#8217;une maladie infectieuse.<\/div>\n<p>Tous les employ\u00e9s couverts par la <a href=\"\/fr\/resource\/quels-types-demploi-ne-sont-pas-vises-par-la-loi\/\" target=\"_blank\" rel=\"noopener\">Loi sur les normes d&#8217;emploi<\/a> peuvent prendre le <a href=\"\/fr\/resource\/cong-sp-cial-en-raison-d-une-maladie-infectieuse-motifs-pour-lesquels-un-employ-peut-prendre-un-cong-sp-cial-en-raison-d-une-maladie-infectieuse\/\" target=\"_blank\" rel=\"noopener\">cong\u00e9 sp\u00e9cial en raison d&#8217;une maladie infectieuse<\/a>. Ce cong\u00e9 vous permet de prendre autant de jours de cong\u00e9 <strong>non pay\u00e9s<\/strong> que n\u00e9cessaire.<\/p>\n<p>Entre le 19 avril 2021 et le 31 mars 2023, vous pouviez \u00e9galement prendre jusqu&#8217;\u00e0 3 jours de cong\u00e9 pay\u00e9s.<\/p>\n<p>Le cong\u00e9 est r\u00e9serv\u00e9 aux <strong>employ\u00e9s<\/strong>. Si vous \u00eates un <a href=\"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/lemployeur-dit-que-je-dois-etre-un-entrepreneur-independant-pourquoi\/\">travailleur ind\u00e9pendant ou un entrepreneur ind\u00e9pendant<\/a>, vous n&#8217;\u00eates pas admissible \u00e0 ce cong\u00e9.<\/p>\n<p>Votre employeur ne peut pas vous licencier, vous menacer ou faire quoi que ce soit d&#8217;autre pour vous punir parce que vous avez choisi de prendre ce cong\u00e9.<\/p>\n<h3>Admissibilit\u00e9 au cong\u00e9 sp\u00e9cial<\/h3>\n<p>Pour b\u00e9n\u00e9ficier du cong\u00e9, l&#8217;<strong>une<\/strong> des conditions suivantes doit s&#8217;appliquer \u00e0 vous :<\/p>\n<ul>\n<li>Vous recevez un vaccin contre la COVID-19 ou vous vous remettez des effets secondaires caus\u00e9s par le vaccin.<\/li>\n<li>Vous recevez des soins en lien avec la COVID-19. Par exemple, vous \u00eates \u00e0 l&#8217;h\u00f4pital.<\/li>\n<li>Vous avez re\u00e7u l&#8217;ordre de vous isoler parce que <a href=\"\/fr\/resource\/si-vous-presentez-des-symptomes-ou-avez-obtenu-un-resultat-positif-a-un-test-de-depistage-de-la-covid-19\/\" target=\"_blank\" rel=\"noopener\">vous avez ou pourriez avoir la COVID-19<\/a>.<\/li>\n<li>Vous avez re\u00e7u l&#8217;ordre de vous isoler parce que <a href=\"\/fr\/resource\/si-vous-vivez-avec-une-personne-qui-presente-des-symptomes-de-la-covid-19\/\" target=\"_blank\" rel=\"noopener\">vous avez \u00e9t\u00e9 en contact avec une personne atteinte de la COVID-19<\/a>.<\/li>\n<li>Votre employeur vous a demand\u00e9 de rester \u00e0 la maison parce que vous pourriez propager la COVID-19 au travail.<\/li>\n<\/ul>\n<p>Vous pouvez \u00e9galement \u00eatre admissible<strong> au cong\u00e9<\/strong> si <a href=\"https:\/\/stepstojustice.ca\/fr\/questions\/covid-19\/puis-je-rester-a-la-maison-pour-prendre-soin-dun-membre-de-la-famille-en-raison-du-covid19\/\">vous devez prendre soin d&#8217;un membre de la famille en raison de la COVID-19<\/a>. Par exemple, vous emmenez votre parent se faire vacciner contre la COVID-19.<\/p>\n<h3>Nombre de jours<\/h3>\n<p>Vous pouvez prendre autant de jours de cong\u00e9 que n\u00e9cessaire. Vous pouvez m\u00eame prendre des cong\u00e9s pour de courtes p\u00e9riodes. Par exemple, vous pouvez aider \u00e0 prendre soin d&#8217;un membre de votre famille un jour par semaine \u00e0 cause de la COVID-19.<\/p>\n<p>Toutefois, vous pouvez le prendre seulement pour la dur\u00e9e dont vous avez besoin. Une fois que vous vous r\u00e9tablissez ou que vous n&#8217;avez plus \u00e0 vous occuper d&#8217;un membre de votre famille, vous devez retourner au travail.<\/p>\n<p>Vous pouvez prendre le cong\u00e9 autant de fois que n\u00e9cessaire. Par exemple, si vous avez pris le cong\u00e9 une fois parce que vous pensiez avoir la COVID-19, vous pourriez le reprendre pour la m\u00eame raison ou parce que vous devez vous occuper d&#8217;un membre de votre famille qui a la COVID-19.<\/p>\n<p>Le gouvernement n&#8217;a pas indiqu\u00e9 \u00e0 quel moment le cong\u00e9 cessera d&#8217;\u00eatre en vigueur.<\/p>\n<h3>Prendre le cong\u00e9<\/h3>\n<p>C&#8217;est votre choix si vous voulez prendre le cong\u00e9 sp\u00e9cial en raison d&#8217;une maladie infectieuse.<\/p>\n<p>La loi dit que votre employeur ne peut pas vous cong\u00e9dier, vous menacer ou faire quoi que ce soit d&#8217;autre pour vous punir parce que vous avez choisi de prendre un cong\u00e9.<\/p>\n<p>Pour prendre le cong\u00e9 sp\u00e9cial en raison d&#8217;une maladie infectieuse, vous devez informer votre employeur de votre situation. Si vous le pouvez, il est pr\u00e9f\u00e9rable de le faire avant de partir en cong\u00e9.<\/p>\n<p>Votre employeur peut demander des preuves \u00ab raisonnables \u00bb. Par exemple, il pourrait demander :<\/p>\n<ul>\n<li>une copie d&#8217;une directive de la sant\u00e9 publique indiquant que vous devez vous isoler, si vous avez une copie de la directive<\/li>\n<li>une note du service de garde de votre enfant indiquant qu&#8217;il est ferm\u00e9 en raison de la COVID-19<\/li>\n<\/ul>\n<p>Votre employeur <strong>peut vous demander<\/strong> une note d&#8217;un m\u00e9decin, mais il <strong>ne peut pas en exiger<\/strong> une. Vous avez le droit de refuser d&#8217;en donner.<\/p>\n<h3>Autres options<\/h3>\n<p>Si vous avez des jours de cong\u00e9s, vous pourrez peut-\u00eatre les utiliser avant de prendre le cong\u00e9 sp\u00e9cial en raison d&#8217;une maladie infectieuse.<\/p>\n<p>Et vous pourriez peut-\u00eatre utiliser des jours de cong\u00e9 de maladie pay\u00e9s, si vous en avez, selon la politique de cong\u00e9 de maladie de votre employeur.<\/p>\n<p>Si vous devez rester \u00e0 la maison pour prendre soin de vos\u00a0<a href=\"\/fr\/questions\/covid-19\/je-dois-rester-a-la-maison-pour-prendre-soin-de-mes-enfants-ou-dun-autre-membre\/\">enfants ou de vos parents<\/a>, vous pourrez peut-\u00eatre demander \u00e0 votre employeur une mesure d&#8217;adaptation bas\u00e9 sur le Code des droits de la personne. Cela pourrait vous permettre de travailler de la maison ou de modifier votre horaire de travail, afin de ne pas prendre le cong\u00e9 sp\u00e9cial en raison d&#8217;une maladie infectieuse.<\/p>\n<p>M\u00eame si vous avez la possibilit\u00e9 d&#8217;obtenir une mesure d&#8217;adaptation, de prendre des cong\u00e9s de maladie pay\u00e9s ou des jours de vacances, cela ne signifie pas que vous devez les utiliser. Vous pouvez choisir de <a href=\"\/fr\/resource\/cong-sp-cial-en-raison-d-une-maladie-infectieuse-motifs-pour-lesquels-un-employ-peut-prendre-un-cong-sp-cial-en-raison-d-une-maladie-infectieuse\/\" target=\"_blank\" rel=\"noopener\">prendre ce cong\u00e9 si c\u2019est ce que vous pr\u00e9f\u00e9rez<\/a>.<\/p>\n<p>Ind\u00e9pendamment de l&#8217;option que vous choisissez, assurez-vous d&#8217;en informer votre employeur <strong>imm\u00e9diatement<\/strong>.<\/p>\n<h3>Obtenir\u00a0de l\u2019assistance\u00a0juridique<\/h3>\n<p>Si vous avez de la difficult\u00e9 \u00e0 vous absenter du travail, vous voudrez peut-\u00eatre\u00a0obtenir une assistance juridique.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","legal-topic":[42145,42219,42222],"class_list":["post-1171387","questions","type-questions","status-publish","hentry","legal-topic-employment-and-work","legal-topic-time-work","legal-topic-sick-and-emergency-leave"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19? - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Vous pourriez \u00eatre admissible aux prestations de maladie de l&#039;assurance-emploi pendant que vous \u00eates en cong\u00e9 sp\u00e9cial en raison d&#039;une maladie infectieuse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19? - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Vous pourriez \u00eatre admissible aux prestations de maladie de l&#039;assurance-emploi pendant que vous \u00eates en cong\u00e9 sp\u00e9cial en raison d&#039;une maladie infectieuse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-06T16:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/employment-and-work\\\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/employment-and-work\\\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\\\/\",\"name\":\"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19? - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2020-09-25T18:02:50+00:00\",\"dateModified\":\"2024-05-06T16:25:01+00:00\",\"description\":\"Vous pourriez \u00eatre admissible aux prestations de maladie de l'assurance-emploi pendant que vous \u00eates en cong\u00e9 sp\u00e9cial en raison d'une maladie infectieuse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/employment-and-work\\\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/employment-and-work\\\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/employment-and-work\\\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19? - Justice pas-\u00e0-pas","description":"Vous pourriez \u00eatre admissible aux prestations de maladie de l'assurance-emploi pendant que vous \u00eates en cong\u00e9 sp\u00e9cial en raison d'une maladie infectieuse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19? - Justice pas-\u00e0-pas","og_description":"Vous pourriez \u00eatre admissible aux prestations de maladie de l'assurance-emploi pendant que vous \u00eates en cong\u00e9 sp\u00e9cial en raison d'une maladie infectieuse.","og_url":"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2024-05-06T16:25:01+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/","url":"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/","name":"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19? - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2020-09-25T18:02:50+00:00","dateModified":"2024-05-06T16:25:01+00:00","description":"Vous pourriez \u00eatre admissible aux prestations de maladie de l'assurance-emploi pendant que vous \u00eates en cong\u00e9 sp\u00e9cial en raison d'une maladie infectieuse.","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/employment-and-work\/a-quel-moment-puis-je-prendre-un-conge-professionnel-en-raison-du-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"\u00c0 quel moment puis-je prendre un cong\u00e9 professionnel en raison du COVID-19?"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"date_fg19r358tw7":"2021-05-14","date_sgrhr9fx3j":"2021-09-23 00:00:00","text_qgvph2rt54":"","text_mb2unyqw82h":"","text_z4722ywvha":"","textarea_i237k2mg4u":"","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"","file_1s3spou4tld":[],"text_0iky8vwgh18v":"marianne.stephens","date_e0vrot0tvds":"2020-09-25 14:02:50 -0400","text_y2tadrpr98":"Edited by marie.koona.","number_98lw0j89q05":"2142","post_0glwwksj820p":[],"questions_to_resources_to":[],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":[]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":55,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171387\/revisions"}],"predecessor-version":[{"id":1263772,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171387\/revisions\/1263772"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1171387"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1171387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}