{"id":1171621,"date":"2017-12-07T16:37:23","date_gmt":"2017-12-07T21:37:23","guid":{"rendered":""},"modified":"2023-06-28T11:17:35","modified_gmt":"2023-06-28T15:17:35","slug":"mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services","status":"publish","type":"questions","link":"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/","title":{"rendered":"Mon propri\u00e9taire\u00a0peut-il couper l&#8217;\u00e9lectricit\u00e9 ou mes autres services publics?"},"content":{"rendered":"<p>La Loi sur la <span class=\"no-glossary\">location<\/span> \u00e0 usage d&#8217;habitation qualifie certains services que vous obtenez chez vous de \u00ab services essentiels \u00bb. Les services essentiels sont les suivants :<\/p>\n<ul>\n<li>l&#8217;eau chaude ou froide,<\/li>\n<li>le combustible,<\/li>\n<li>l&#8217;\u00e9lectricit\u00e9,<\/li>\n<li>le gaz naturel,<\/li>\n<li>le chauffage, du 1er septembre au 15 juin.<\/li>\n<\/ul>\n<p>C&#8217;est ill\u00e9gal pour votre <span class=\"no-glossary\">propri\u00e9taire<\/span> de couper ou d&#8217;interf\u00e9rer avec un service essentiel.<\/p>\n<p>La m\u00eame r\u00e8gle s&#8217;applique aux repas et aux <a href=\"\/fr\/resource\/maisons-de-soins\/\" target=\"_blank\" rel=\"noopener\">services de soins<\/a>.<\/p>\n<p>Votre <span class=\"no-glossary\">propri\u00e9taire<\/span> n&#8217;est pas autoris\u00e9 \u00e0 interrompre ou \u00e0 interf\u00e9rer avec ces services pour quelque raison que ce soit, m\u00eame si vous devez un loyer.<\/p>\n<h3>Autres services<\/h3>\n<p>Des services comme l&#8217;Internet, la climatisation, la blanchisserie et un t\u00e9l\u00e9phone fixe ne sont <strong>pas<\/strong> des services essentiels. Mais vous pouvez toujours prendre les m\u00eames mesures que celles mentionn\u00e9es dans cette question si votre <span class=\"no-glossary\">propri\u00e9taire<\/span> les interrompt. La diff\u00e9rence entre les services essentiels et les autres services est que la Commission de la location immobili\u00e8re (CLI) ou l&#8217;Unit\u00e9 d&#8217;application des mesures legislatives en mati\u00e8re de logement locatif (UAML) peuvent <span class=\"glossary\">ordonner<\/span> des sanctions plus s\u00e9v\u00e8res lorsque les propri\u00e9taires coupent ou interf\u00e8rent avec les services essentiels.<\/p>\n<p>Si votre <span class=\"no-glossary\">propri\u00e9taire<\/span> menace de couper votre climatisation, vous devriez d&#8217;abord lire la question <a href=\"\/fr\/steps\/housing-law\/1-sachez-si-votre-proprietaire-peut-vous-empecher-davoir-un-climatiseur\/\" target=\"_blank\" rel=\"noopener\">Quelles sont les r\u00e8gles entourant les climatiseurs?<\/a> pour savoir si votre <span class=\"no-glossary\">propri\u00e9taire<\/span> peut vous emp\u00eacher d&#8217;avoir un climatiseur.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","legal-topic":[42148,42351,42352,42353,42355],"class_list":["post-1171621","questions","type-questions","status-publish","hentry","legal-topic-housing-law","legal-topic-repairs-maintenance","legal-topic-landlord-and-tenant-responsibilities","legal-topic-heat-and-utilities","legal-topic-complaints-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mon propri\u00e9taire\u00a0peut-il couper l&#039;\u00e9lectricit\u00e9 ou mes autres services publics? - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"La Loi sur la location \u00e0 usage d&#039;habitation qualifie certains services que vous obtenez chez vous de \u00ab services essentiels \u00bb. Les services essentiels sont\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mon propri\u00e9taire\u00a0peut-il couper l&#039;\u00e9lectricit\u00e9 ou mes autres services publics? - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"La Loi sur la location \u00e0 usage d&#039;habitation qualifie certains services que vous obtenez chez vous de \u00ab services essentiels \u00bb. Les services essentiels sont\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T15:17:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/housing-law\\\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/housing-law\\\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\\\/\",\"name\":\"Mon propri\u00e9taire\u00a0peut-il couper l'\u00e9lectricit\u00e9 ou mes autres services publics? - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2017-12-07T21:37:23+00:00\",\"dateModified\":\"2023-06-28T15:17:35+00:00\",\"description\":\"La Loi sur la location \u00e0 usage d'habitation qualifie certains services que vous obtenez chez vous de \u00ab services essentiels \u00bb. Les services essentiels sont\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/housing-law\\\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/housing-law\\\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/housing-law\\\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mon propri\u00e9taire\u00a0peut-il couper l&#8217;\u00e9lectricit\u00e9 ou mes autres services publics?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mon propri\u00e9taire\u00a0peut-il couper l'\u00e9lectricit\u00e9 ou mes autres services publics? - Justice pas-\u00e0-pas","description":"La Loi sur la location \u00e0 usage d'habitation qualifie certains services que vous obtenez chez vous de \u00ab services essentiels \u00bb. Les services essentiels sont","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/","og_locale":"fr_FR","og_type":"article","og_title":"Mon propri\u00e9taire\u00a0peut-il couper l'\u00e9lectricit\u00e9 ou mes autres services publics? - Justice pas-\u00e0-pas","og_description":"La Loi sur la location \u00e0 usage d'habitation qualifie certains services que vous obtenez chez vous de \u00ab services essentiels \u00bb. Les services essentiels sont","og_url":"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2023-06-28T15:17:35+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/","url":"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/","name":"Mon propri\u00e9taire\u00a0peut-il couper l'\u00e9lectricit\u00e9 ou mes autres services publics? - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2017-12-07T21:37:23+00:00","dateModified":"2023-06-28T15:17:35+00:00","description":"La Loi sur la location \u00e0 usage d'habitation qualifie certains services que vous obtenez chez vous de \u00ab services essentiels \u00bb. Les services essentiels sont","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/housing-law\/mon-proprietaire-peut-il-couper-lelectricite-ou-mes-autres-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"Mon propri\u00e9taire\u00a0peut-il couper l&#8217;\u00e9lectricit\u00e9 ou mes autres services publics?"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"date_fg19r358tw7":"2015-08-31 00:00:00","date_sgrhr9fx3j":"2018-12-07 00:00:00","text_qgvph2rt54":"","text_mb2unyqw82h":"","text_z4722ywvha":"","textarea_i237k2mg4u":"TH - 2018 04 26: Changed all instances of \"locateur\" to \"propri\u00e9taire\".","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"Jan 2018: Changed S2J links to the French pages.","file_1s3spou4tld":[],"text_0iky8vwgh18v":"marianne.stephens","date_e0vrot0tvds":"2017-12-07 16:37:23 -0500","text_y2tadrpr98":"added primary topic field","number_98lw0j89q05":"11734","post_0glwwksj820p":[1171455,1171640,1171682],"questions_to_resources_to":[1197959,1185831,1181914],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":[1177976,1177977,1177978,1177963,1177962]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":9,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171621\/revisions"}],"predecessor-version":[{"id":1253456,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171621\/revisions\/1253456"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1171621"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1171621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}