{"id":1171819,"date":"2018-11-27T15:48:03","date_gmt":"2018-11-27T20:48:03","guid":{"rendered":""},"modified":"2024-07-02T08:30:03","modified_gmt":"2024-07-02T12:30:03","slug":"je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en","status":"publish","type":"questions","link":"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/","title":{"rendered":"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario?"},"content":{"rendered":"<p>En Ontario, la Loi sur les services en fran\u00e7ais pr\u00e9cise que vous avez le droit d&#8217;obtenir des services en fran\u00e7ais du gouvernement provincial. Si vous r\u00e9sidez dans l&#8217;une des <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/carte-des-r-gions-d-sign-es-de-l-ontario\/\" target=\"_blank\" rel=\"noopener\">27 zones d\u00e9sign\u00e9es<\/a>,\u00a0vous pouvez obtenir ces services\u00a0aupr\u00e8s :<\/p>\n<ul>\n<li>de 28 minist\u00e8res du gouvernement de l&#8217;Ontario ;<\/li>\n<li>des organismes gouvernementaux qui travaillent pour le compte des minist\u00e8res ;<\/li>\n<li>des organismes financ\u00e9s par le gouvernement ;\u00a0et<\/li>\n<li>des personnes tierces qui offrent des services pour le compte du gouvernement.<\/li>\n<\/ul>\n<p>Les services en fran\u00e7ais incluent les services fournis en personne, par t\u00e9l\u00e9phone, par voie \u00e9lectronique (par courriel) et par \u00e9crit. Vous devez avoir le <span class=\"no-glossary\">choix<\/span> d&#8217;utiliser l&#8217;une ou l&#8217;autre langue d\u00e8s le premier contact. Un exemple de ceci est l&#8217;utilisation de \u00ab Hello-Bonjour \u00bb.\u00a0Cela s&#8217;appelle parfois l&#8217;offre active.<\/p>\n<p>Si vous habitez \u00e0 l&#8217;ext\u00e9rieur d&#8217;une r\u00e9gion d\u00e9sign\u00e9e, vous avez toujours le droit d&#8217;obtenir des services en fran\u00e7ais, mais pas forc\u00e9ment dans votre r\u00e9gion. Cela d\u00e9pend de ressources comme\u00a0la disponibilit\u00e9 du personnel francophone. Il se peut que vous deviez avoir acc\u00e8s \u00e0 des services en fran\u00e7ais au si\u00e8ge social ou ailleurs.<\/p>\n<h3>Organismes\u00a0et services d\u00e9sign\u00e9s<\/h3>\n<p>Il y a 243 <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/loi-sur-les-services-en-fran-ais\/\" target=\"_blank\" rel=\"noopener\">organismes d\u00e9sign\u00e9s des gouvernements provinciaux<\/a> qui doivent fournir des services en fran\u00e7ais. La loi n&#8217;oblige pas certains de ces organismes \u00e0 fournir ces services\u00a0m\u00eame s&#8217;ils ont demand\u00e9 et obtenu une d\u00e9signation en fran\u00e7ais.<\/p>\n<p>Ci-dessous des\u00a0exemples d&#8217;organismes pouvant \u00eatre d\u00e9sign\u00e9s :<\/p>\n<ul>\n<li>les soci\u00e9t\u00e9s d&#8217;aide \u00e0 l&#8217;enfance ;<\/li>\n<li>les h\u00f4pitaux ;<\/li>\n<li>les coll\u00e8ges et les universit\u00e9s ;<\/li>\n<li>les r\u00e9sidences pour personnes \u00e2g\u00e9es.<\/li>\n<\/ul>\n<h3>Services Municipaux<\/h3>\n<p>Les municipalit\u00e9s ne sont pas tenues d&#8217;offrir des services en fran\u00e7ais, m\u00eame dans certaines r\u00e9gions d\u00e9sign\u00e9es, bien que certaines le fassent. Et une municipalit\u00e9 peut adopter un r\u00e8glement pr\u00e9voyant que tout ou une partie de ses services au public sont offerts dans les deux langues.<\/p>\n<h3>Les plaintes<\/h3>\n<p>Si vous n&#8217;obtenez pas de services en fran\u00e7ais du gouvernement provincial ou municipal (le cas \u00e9ch\u00e9ant) ou de l&#8217;un de ses organismes d\u00e9sign\u00e9s, ou si le service n&#8217;est pas satisfaisant, vous pouvez <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/formulaire-de-plainte\/\" target=\"_blank\" rel=\"noopener\">d\u00e9poser une plainte<\/a> aupr\u00e8s de l&#8217;<a class=\"links-link ext new-link\" href=\"\/fr\/resource\/unit-des-services-en-fran-ais-de-l-ombudsman-de-l-ontario\/\" target=\"_blank\" rel=\"noopener\">Unit\u00e9 des services en francais de l&#8217;Ombudsman de l&#8217;Ontario<\/a>.<\/p>\n<h3>Services f\u00e9d\u00e9raux<\/h3>\n<p>Si vous faites affaire avec un <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/minist-res-et-organismes\/\" target=\"_blank\" rel=\"noopener\">minist\u00e8re ou un organisme du gouvernement f\u00e9d\u00e9ral<\/a>, la Loi sur les langues officielles du Canada pr\u00e9cise que vous avez toujours le droit d&#8217;obtenir des services en fran\u00e7ais. Cela inclut des services pour\u00a0:<\/p>\n<ul>\n<li>les prestations f\u00e9d\u00e9rales telles que l&#8217;assurance-emploi, le R\u00e9gime de pensions du Canada, le programme de la S\u00e9curit\u00e9 de la vieillesse ;<\/li>\n<li>l&#8217;immigration et la citoyennet\u00e9 ;<\/li>\n<li>le droit criminel.<\/li>\n<\/ul>\n<p>Si vous n&#8217;obtenez pas de services en fran\u00e7ais d&#8217;un minist\u00e8re ou d&#8217;un organisme du gouvernement f\u00e9d\u00e9ral, ou si le service n&#8217;est pas ad\u00e9quat, vous pouvez d\u00e9poser une plainte aupr\u00e8s du <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/commissariat-aux-langues-officielles-1\/\" target=\"_blank\" rel=\"noopener\">Commissariat aux langues officielles<\/a>.<\/p>\n<h3>Les droits linguistiques des francophones dans votre\u00a0affaire juridique<\/h3>\n<p>Il existe une diff\u00e9rence entre le droit d&#8217;obtenir des services en fran\u00e7ais et le droit de recourir au\u00a0fran\u00e7ais dans votre affaire.<\/p>\n<p>Votre droit d&#8217;utiliser le fran\u00e7ais dans votre proc\u00e9dure judiciaire est un droit linguistique qui d\u00e9pend si vous \u00eates :<\/p>\n<ul>\n<li><a href=\"\/fr\/questions\/french-language-rights\/mon-proces-criminel-peut-il-se-derouler-en-francais-2\/\">\u00e0 la Cour criminelle<\/a> ;<\/li>\n<li><a href=\"\/fr\/questions\/french-language-rights\/mon-proces-en-droit-de-la-famille-peut-il-se-derouler-en-francais\/\">\u00e0 la Cour de la famille<\/a>\u00a0;<\/li>\n<li><a href=\"\/fr\/questions\/french-language-rights\/mon-proces-civil-peut-il-se-derouler-en-francais\/\">\u00e0 la Cour des petites cr\u00e9ances<\/a>\u00a0;<\/li>\n<li><a href=\"\/fr\/questions\/french-language-rights\/mon-proces-civil-peut-il-se-derouler-en-francais\/\">\u00e0 une instance judiciaire bilingue pour les affaires civiles sans jury<\/a>\u00a0;<\/li>\n<li>\u00e0 l&#8217;un des <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/services-en-francais\/\" target=\"_blank\" rel=\"noopener\">tribunaux d\u00e9cisionnels de l&#8217;Ontario.<\/a><\/li>\n<\/ul>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","legal-topic":[42575,43713],"class_list":["post-1171819","questions","type-questions","status-publish","hentry","legal-topic-french-language-rights","legal-topic-getting-help-fr-lang"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario? - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"En Ontario, la Loi sur les services en fran\u00e7ais pr\u00e9cise que vous avez le droit d&#039;obtenir des services en fran\u00e7ais du gouvernement provincial. Si vous\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario? - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"En Ontario, la Loi sur les services en fran\u00e7ais pr\u00e9cise que vous avez le droit d&#039;obtenir des services en fran\u00e7ais du gouvernement provincial. Si vous\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T12:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/french-language-rights\\\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/french-language-rights\\\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\\\/\",\"name\":\"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario? - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2018-11-27T20:48:03+00:00\",\"dateModified\":\"2024-07-02T12:30:03+00:00\",\"description\":\"En Ontario, la Loi sur les services en fran\u00e7ais pr\u00e9cise que vous avez le droit d'obtenir des services en fran\u00e7ais du gouvernement provincial. Si vous\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/french-language-rights\\\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/french-language-rights\\\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/french-language-rights\\\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/questions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario? - Justice pas-\u00e0-pas","description":"En Ontario, la Loi sur les services en fran\u00e7ais pr\u00e9cise que vous avez le droit d'obtenir des services en fran\u00e7ais du gouvernement provincial. Si vous","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/","og_locale":"fr_FR","og_type":"article","og_title":"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario? - Justice pas-\u00e0-pas","og_description":"En Ontario, la Loi sur les services en fran\u00e7ais pr\u00e9cise que vous avez le droit d'obtenir des services en fran\u00e7ais du gouvernement provincial. Si vous","og_url":"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2024-07-02T12:30:03+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/","url":"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/","name":"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario? - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2018-11-27T20:48:03+00:00","dateModified":"2024-07-02T12:30:03+00:00","description":"En Ontario, la Loi sur les services en fran\u00e7ais pr\u00e9cise que vous avez le droit d'obtenir des services en fran\u00e7ais du gouvernement provincial. Si vous","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/french-language-rights\/je-parle-francais-quels-sont-mes-droits-aux-services-en-francais-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"Je parle fran\u00e7ais. Quels sont mes droits aux services en fran\u00e7ais en Ontario?"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"date_fg19r358tw7":"2021-12-14","date_sgrhr9fx3j":"2019-11-27 00:00:00","text_qgvph2rt54":"","text_mb2unyqw82h":"","text_z4722ywvha":"","textarea_i237k2mg4u":"December 14, 2021 FW number of designated areas increased from 26 to 27","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"","file_1s3spou4tld":[],"text_0iky8vwgh18v":"marianne.stephens","date_e0vrot0tvds":"2018-11-27 15:48:03 -0500","text_y2tadrpr98":"Edited by marie.koona.","number_98lw0j89q05":"2925","post_0glwwksj820p":[1205003,1204852,1204884],"questions_to_resources_to":[1186878,1181814],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":[1175442,1175443,1175444,1175445]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":13,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171819\/revisions"}],"predecessor-version":[{"id":1265326,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171819\/revisions\/1265326"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1171819"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1171819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}