{"id":1202825,"date":"2021-05-27T12:54:46","date_gmt":"2021-05-27T16:54:46","guid":{"rendered":"https:\/\/stepstojustice.ca\/?post_type=questions&#038;p=1202825"},"modified":"2021-12-10T12:32:39","modified_gmt":"2021-12-10T17:32:39","slug":"jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options","status":"publish","type":"questions","link":"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/","title":{"rendered":"J&#8217;ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options?"},"content":{"rendered":"<p>Les contraventions de stationnement ou pour infraction au Code de la route sont donn\u00e9es en cas d&#8217;infraction provinciale. Une infraction provinciale n&#8217;est pas un \u00ab crime \u00bb au sens du droit criminel; vous n&#8217;aurez donc<strong> pas<\/strong> de casier judiciaire, mais vous pourriez devoir payer une amende et m\u00eame faire de la prison.<\/p>\n<p>Vous pouvez avoir une contravention pour diff\u00e9rentes raisons : exc\u00e8s de vitesse, stationnement non autoris\u00e9, man\u0153uvres p\u00e9rilleuses, absence d&#8217;assurances, etc.<\/p>\n<h3>Types de contravention<\/h3>\n<p>Il existe 3 types de contravention. C&#8217;est important de faire la diff\u00e9rence, car leur degr\u00e9 de gravit\u00e9 varie, et vos options aussi. Voici les 3 types :<\/p>\n<ul>\n<li>L&#8217;<strong>avis d&#8217;infraction de stationnement<\/strong> ou toute autre contravention de stationnement, que vous pouvez payer en ligne ou par la poste. C&#8217;est le type le moins s\u00e9v\u00e8re.<\/li>\n<li>L&#8217;<strong>avis d&#8217;infraction<\/strong>, pour les infractions provinciales moins graves, comme un exc\u00e8s de vitesse mineur. L&#8217;amende maximale est de 1 000 $. Vous pouvez payer en ligne ou par la poste.<\/li>\n<li>L&#8217;<strong>assignation<\/strong>, pour les infractions provinciales graves, par exemple si vous avez fait des man\u0153uvres p\u00e9rilleuses en voiture. Vous devrez alors aller au tribunal. Le processus ressemble \u00e0 un proc\u00e8s criminel.<\/li>\n<\/ul>\n<p>Lisez ce qui est \u00e9crit en haut de la contravention pour savoir de quel type il s&#8217;agit.<\/p>\n<h3>Quoi faire avec une contravention<\/h3>\n<p>Vos options d\u00e9pendent du type de contravention que vous avez re\u00e7u. Elles sont inscrites au verso du document.<\/p>\n<p>Si vous croyez ne rien avoir fait qui m\u00e9rite une contravention, vous pouvez contester celle-ci en demandant un proc\u00e8s.<\/p>\n<p>Si vous ne le faites pas et que vous ne payez pas l&#8217;amende, le gouvernement peut suspendre votre permis de conduire, refuser d&#8217;immatriculer votre v\u00e9hicule, augmenter le montant de l&#8217;amende, ou m\u00eame c\u00e9der la dette \u00e0 une <a href=\"\/fr\/questions\/debt-and-consumer-rights\/une-agence-de-recouvrement-mappelle-au-sujet-dun\">agence de recouvrement<\/a>.<\/p>\n<h3>Demander de l&#8217;information et de l&#8217;assistance juridique<\/h3>\n<p>Pour conna\u00eetre l&#8217;\u00e9tat de votre contravention, allez au <a href=\"\/fr\/resource\/verifiez-en-ligne-letat-de-vos-contraventions-et-amendes-pour-infractions-routieres-ou-demandez-une-rencontre-pour-regler-votre-dossier\/\" target=\"_blank\" rel=\"noopener\">ontario.ca\/contraventionsetamendes<\/a>.<\/p>\n<p>Pour conna\u00eetre le fonctionnement g\u00e9n\u00e9ral des affaires d&#8217;infraction provinciale, vous pouvez t\u00e9l\u00e9charger le <a href=\"\/fr\/resource\/guide-pour-les-defendeurs-dans-les-causes-liees-aux-infractions-provinciales\/\" target=\"_blank\" rel=\"noopener\">Guide pour les d\u00e9fendeurs dans les causes li\u00e9es aux infractions provinciales<\/a>.<\/p>\n<p>Si vous avez re\u00e7u une contravention pour exc\u00e8s de vitesse, vous devriez peut-\u00eatre demander les <a href=\"\/fr\/questions\/tribunals-and-courts\/comment-faire-pour-trouver-un-avocat-ou-un-parajuriste-qui-peut\">conseils juridiques d&#8217;un avocat ou d&#8217;un parajuriste<\/a> sur les <a href=\"\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-pour-exces-de-vitesse-quelles-sont-les-consequences\/\">cons\u00e9quences que cela peut avoir pour vous<\/a> et sur vos options.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":6,"featured_media":0,"template":"","legal-topic":[43878,43873],"class_list":["post-1202825","questions","type-questions","status-publish","hentry","legal-topic-provincial-offences","legal-topic-tickets"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>J&#039;ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options? - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Les contraventions de stationnement ou pour infraction au Code de la route sont donn\u00e9es en cas d&#039;infraction provinciale. Une infraction provinciale n&#039;est\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J&#039;ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options? - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Les contraventions de stationnement ou pour infraction au Code de la route sont donn\u00e9es en cas d&#039;infraction provinciale. Une infraction provinciale n&#039;est\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-10T17:32:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/\",\"name\":\"J'ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options? - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"2021-05-27T16:54:46+00:00\",\"dateModified\":\"2021-12-10T17:32:39+00:00\",\"description\":\"Les contraventions de stationnement ou pour infraction au Code de la route sont donn\u00e9es en cas d'infraction provinciale. Une infraction provinciale n'est\",\"breadcrumb\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/questions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"J&#8217;ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"contentUrl\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CLEOLegalRights\/\",\"https:\/\/x.com\/CLEOLegalRights\",\"https:\/\/www.instagram.com\/communitylegaleducationon\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"J'ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options? - Justice pas-\u00e0-pas","description":"Les contraventions de stationnement ou pour infraction au Code de la route sont donn\u00e9es en cas d'infraction provinciale. Une infraction provinciale n'est","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/","og_locale":"fr_FR","og_type":"article","og_title":"J'ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options? - Justice pas-\u00e0-pas","og_description":"Les contraventions de stationnement ou pour infraction au Code de la route sont donn\u00e9es en cas d'infraction provinciale. Une infraction provinciale n'est","og_url":"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2021-12-10T17:32:39+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/","url":"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/","name":"J'ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options? - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2021-05-27T16:54:46+00:00","dateModified":"2021-12-10T17:32:39+00:00","description":"Les contraventions de stationnement ou pour infraction au Code de la route sont donn\u00e9es en cas d'infraction provinciale. Une infraction provinciale n'est","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/provincial-offences\/jai-recu-une-contravention-de-stationnement-ou-pour-infraction-au-code-de-la-route-quelles-sont-mes-options\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"J&#8217;ai re\u00e7u une contravention de stationnement ou pour infraction au Code de la route. Quelles sont mes options?"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"date_fg19r358tw7":"2021-03-01","date_sgrhr9fx3j":"","text_qgvph2rt54":"","text_mb2unyqw82h":"Andrew Hills","text_z4722ywvha":"","textarea_i237k2mg4u":"Marnie Hudswell (minist\u00e8re du Procureur g\u00e9n\u00e9ral) et Raphael Leong (minist\u00e8re du Procureur g\u00e9n\u00e9ral)","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"","file_1s3spou4tld":[{"icon":"<img width=\"48\" height=\"64\" src=\"https:\/\/stepstojustice.ca\/wp-includes\/images\/media\/document.png\" alt=\"\">","name":"POA-Parking-and-Traffic-_-final-_-March-2021_FR.docx","path":"\/home\/stepstojustice\/public_html\/system\/files\/POA-Parking-and-Traffic-_-final-_-March-2021_FR.docx","url":"https:\/\/stepstojustice.ca\/system\/files\/POA-Parking-and-Traffic-_-final-_-March-2021_FR.docx","title":"POA-Parking-and-Traffic-_-final-_-March-2021_FR","edit_link":""}],"text_0iky8vwgh18v":"","date_e0vrot0tvds":"","text_y2tadrpr98":"","number_98lw0j89q05":"2862","post_0glwwksj820p":[1202829,1171804,1202827],"questions_to_resources_to":["1202387","1185513"],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":["1202920","1202938","1202941","1202944"]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1202825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":13,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1202825\/revisions"}],"predecessor-version":[{"id":1228517,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1202825\/revisions\/1228517"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1202825"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1202825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}