{"id":1277592,"date":"2026-02-25T09:28:50","date_gmt":"2026-02-25T14:28:50","guid":{"rendered":"https:\/\/stepstojustice.ca\/questions\/\/where-can-i-get-legal-help-with-wills-powers-of-attorney-and-managing-an-estate\/"},"modified":"2026-03-11T15:19:22","modified_gmt":"2026-03-11T19:19:22","slug":"ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession","status":"publish","type":"questions","link":"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/","title":{"rendered":"O\u00f9 trouver de l&#8217;assistance juridique concernant les testaments, les procurations ou la gestion d&#8217;une succession?"},"content":{"rendered":"\n<p>Cette question vous pr\u00e9sente des renseignements sur comment trouver un(e) avocat(e) si vous avez des interrogations concernant&nbsp;:<\/p>\n<ul>\n<li>les testaments et les procurations;<\/li>\n<li>la planification successorale;<\/li>\n<li>vos fonctions de fiduciaire de la succession.<\/li>\n<\/ul>\n<p>Elle pr\u00e9sente aussi des renseignements sur comment trouver de l\u2019assistance gratuite ou \u00e0 faible co\u00fbt si vous n\u2019avez pas les moyens de payer un(e) avocat(e).<\/p>\n<h3>Pr\u00e9parer un testament ou une procuration<\/h3>\n<p>Il est recommand\u00e9 de demander l\u2019aide d\u2019un(e) avocat(e) en droit successoral si vous souhaitez pr\u00e9parer&nbsp;:<\/p>\n<ul>\n<li>un testament;<\/li>\n<li>une <span><a href=\"\/fr\/legal-topic\/wills-and-powers-of-attorney\/power-of-attorney-for-property\/\">procuration relative aux biens<\/a><\/span> pour nommer une personne de confiance, qui prendra les d\u00e9cisions sur vos biens;<\/li>\n<li>une <span><a href=\"\/fr\/questions\/wills-and-powers-of-attorney\/ai-je-besoin-dune-procuration-relative-au-soin-de-la-personne\/\">procuration relative au soin de la personne<\/a><\/span> pour nommer une personne de confiance, qui prendra les d\u00e9cisions au sujet de vos soins si vous devenez mentalement incapable.<\/li>\n<\/ul>\n<p>Un(e) avocat(e) en droit successoral peut aussi vous conseiller et vous aider \u00e0 r\u00e9duire vos frais d\u2019homologation.<\/p>\n<p>Vous pouvez aussi consulter un conseiller financier, un comptable ou votre institution financi\u00e8re si vous devez g\u00e9rer une succession complexe ou de grande taille.<\/p>\n<h3>Agir comme fiduciaire de la succession<\/h3>\n<p>Un(e) avocat(e) en droit successoral peut vous conseiller si l\u2019on vous d\u00e9signe comme fiduciaire de la succession ou mandataire par procuration. Il peut vous expliquer vos responsabilit\u00e9s et g\u00e9rer votre risque juridique.<\/p>\n<p>Il peut aussi vous donner des conseils juridiques si votre \u00eatre cher d\u00e9c\u00e8de sans testament et vous souhaitez faire une demande pour devenir fiduciaire de sa succession.<\/p>\n<h3>Autres types d\u2019assistance<\/h3>\n<p>Un(e) avocat(e) en droit successoral peut vous aider dans d\u2019autres situations. Par exemple, une personne qui vous soutient financi\u00e8rement d\u00e9c\u00e8de sans rien vous laisser dans son testament. Un(e) avocat(e) en droit successoral peut vous dire si vous pouvez faire une demande pour obtenir de l\u2019aide financi\u00e8re \u00e0 m\u00eame la succession.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":6,"featured_media":0,"template":"","legal-topic":[42152,45110],"class_list":["post-1277592","questions","type-questions","status-publish","hentry","legal-topic-wills-and-powers-of-attorney","legal-topic-get-legal-help"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O\u00f9 trouver de l&#039;assistance juridique concernant les testaments, les procurations ou la gestion d&#039;une succession? - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Cette question vous pr\u00e9sente des renseignements sur comment trouver un(e) avocat(e) si vous avez des interrogations concernant&nbsp;: les testaments et\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u00f9 trouver de l&#039;assistance juridique concernant les testaments, les procurations ou la gestion d&#039;une succession? - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Cette question vous pr\u00e9sente des renseignements sur comment trouver un(e) avocat(e) si vous avez des interrogations concernant&nbsp;: les testaments et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T19:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/\",\"name\":\"O\u00f9 trouver de l'assistance juridique concernant les testaments, les procurations ou la gestion d'une succession? - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"2026-02-25T14:28:50+00:00\",\"dateModified\":\"2026-03-11T19:19:22+00:00\",\"description\":\"Cette question vous pr\u00e9sente des renseignements sur comment trouver un(e) avocat(e) si vous avez des interrogations concernant&nbsp;: les testaments et\",\"breadcrumb\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/questions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O\u00f9 trouver de l&#8217;assistance juridique concernant les testaments, les procurations ou la gestion d&#8217;une succession?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"contentUrl\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CLEOLegalRights\/\",\"https:\/\/x.com\/CLEOLegalRights\",\"https:\/\/www.instagram.com\/communitylegaleducationon\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O\u00f9 trouver de l'assistance juridique concernant les testaments, les procurations ou la gestion d'une succession? - Justice pas-\u00e0-pas","description":"Cette question vous pr\u00e9sente des renseignements sur comment trouver un(e) avocat(e) si vous avez des interrogations concernant&nbsp;: les testaments et","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/","og_locale":"fr_FR","og_type":"article","og_title":"O\u00f9 trouver de l'assistance juridique concernant les testaments, les procurations ou la gestion d'une succession? - Justice pas-\u00e0-pas","og_description":"Cette question vous pr\u00e9sente des renseignements sur comment trouver un(e) avocat(e) si vous avez des interrogations concernant&nbsp;: les testaments et","og_url":"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2026-03-11T19:19:22+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/","url":"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/","name":"O\u00f9 trouver de l'assistance juridique concernant les testaments, les procurations ou la gestion d'une succession? - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2026-02-25T14:28:50+00:00","dateModified":"2026-03-11T19:19:22+00:00","description":"Cette question vous pr\u00e9sente des renseignements sur comment trouver un(e) avocat(e) si vous avez des interrogations concernant&nbsp;: les testaments et","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/ou-trouver-de-lassistance-juridique-concernant-les-testaments-les-procurations-ou-la-gestion-dune-succession\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"O\u00f9 trouver de l&#8217;assistance juridique concernant les testaments, les procurations ou la gestion d&#8217;une succession?"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"date_fg19r358tw7":"2025-12-19","date_sgrhr9fx3j":"","text_qgvph2rt54":"","text_mb2unyqw82h":"Maria Alexiou","text_z4722ywvha":"Carina Vincent","textarea_i237k2mg4u":"Name of external reviewer(s):  Zara Wong ","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"","file_1s3spou4tld":[],"text_0iky8vwgh18v":"","date_e0vrot0tvds":"","text_y2tadrpr98":"","number_98lw0j89q05":"171","post_0glwwksj820p":[],"questions_to_resources_to":[],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":[]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1277592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":2,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1277592\/revisions"}],"predecessor-version":[{"id":1277594,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1277592\/revisions\/1277594"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1277592"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1277592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}