{"id":1175571,"date":"2019-08-08T16:07:01","date_gmt":"2019-08-08T20:07:01","guid":{"rendered":""},"modified":"2021-10-01T11:23:52","modified_gmt":"2021-10-01T15:23:52","slug":"4-demandez-un-numero-dassurance-sociale-nas","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/","title":{"rendered":"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS)"},"content":{"rendered":"<p>Si Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) approuve votre demande de permis de travail ouvert, vous pourrez demander un num\u00e9ro d\u2019assurance sociale (NAS) aupr\u00e8s de Service Canada.<\/p>\n<p>Le NAS vous permet de travailler en toute l\u00e9galit\u00e9, de payer vos imp\u00f4ts et d\u2019utiliser les services gouvernementaux au Canada.<\/p>\n<p>Pour demander un NAS, la plupart des gens doivent se rendre au <a class=\"links-link ext\" href=\"\/fr\/resource\/trouver-un-bureau-de-service-canada-1-1\/\" target=\"_blank\" rel=\"noopener\">bureau de Service Canada de leur r\u00e9gion<\/a>. Si vous vivez \u00e0 plus de 100\u00a0kilom\u00e8tres du bureau le plus pr\u00e8s, ou si un <a class=\"links-link ext\" href=\"\/fr\/resource\/num-ro-d-assurance-sociale-pr-senter-une-demande\/\" target=\"_blank\" rel=\"noopener\">autre facteur<\/a> vous emp\u00eache de vous y rendre en personne, vous pourriez \u00eatre autoris\u00e9 \u00e0 faire votre demande en ligne ou par la poste.<\/p>\n<p>Vous pouvez t\u00e9l\u00e9charger le <a class=\"links-link ext\" href=\"\/fr\/resource\/application-for-a-social-insurance-number-1\/\" target=\"_blank\" rel=\"noopener\">formulaire de demande<\/a> ou en obtenir un dans un <a class=\"links-link ext\" href=\"\/fr\/resource\/trouver-un-bureau-de-service-canada-1-1\/\" target=\"_blank\" rel=\"noopener\">bureau de Service Canada<\/a>. Joignez-y\u00a0:<\/p>\n<ul>\n<li>votre document du demandeur d\u2019asile;<\/li>\n<li>un autre document qui montre votre nom, comme un certificat de naissance, un certificat de mariage ou une ordonnance de divorce;<\/li>\n<li>l\u2019original de votre permis de travail.<\/li>\n<\/ul>\n<p>Si vos documents sont dans une autre langue que l\u2019anglais ou le fran\u00e7ais, vous devez aussi avoir\u00a0:<\/p>\n<ul>\n<li>une traduction anglaise ou fran\u00e7aise du document;<\/li>\n<li>une d\u00e9claration ou un affidavit \u00e9crit et sign\u00e9 par le traducteur.<\/li>\n<\/ul>\n<p>Si vous faites votre demande en personne, d\u00e9posez votre formulaire rempli et l\u2019original de votre permis de travail au bureau de Service Canada le plus pr\u00e8s. Si votre demande est compl\u00e8te, vous obtiendrez tout de suite votre NAS.<\/p>\n<p>Si vous faites votre demande par la poste, remplissez le formulaire et envoyez-le avec l\u2019original de votre permis de travail. Les photocopies ne sont pas accept\u00e9es, mais vous pouvez en faire pour vous-m\u00eame.<\/p>\n<p>Envoyer votre demande \u00e0\u00a0:<\/p>\n<p>Service Canada<\/p>\n<p>Bureau d&#8217;immatriculation aux assurances sociales<\/p>\n<p>Case postale 7000<\/p>\n<p>Bathurst (Nouveau-Brunswick)\u00a0 E2A 4T1<\/p>\n<p>Conservez une copie de votre permis de travail ouvert. Service Canada vous renverra l\u2019original.<\/p>\n<p>Si votre demande est compl\u00e8te, vous recevrez par la poste une lettre contenant votre NAS dans les 20\u00a0jours ouvrables suivant la date de r\u00e9ception de votre demande. Si plus de 25\u00a0jours ouvrables se sont \u00e9coul\u00e9s, vous pouvez communiquer avec Service Canada pour <a class=\"links-link ext\" href=\"\/fr\/resource\/contact-social-insurance-number\/\" target=\"_blank\" rel=\"noopener\">conna\u00eetre l\u2019\u00e9tat<\/a> de votre demande.<\/p>\n<p>Votre NAS sera compos\u00e9 de neuf chiffres et commencera par \u00ab\u00a09\u00a0\u00bb. Il est temporaire et viendra \u00e0 \u00e9ch\u00e9ance en m\u00eame temps que votre permis de travail. Si vous devez prolonger votre permis de travail, faites une demande \u00e0 IRCC au moins 30\u00a0jours avant son \u00e9ch\u00e9ance.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1175571","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS) - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Si Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) approuve votre demande de permis de travail ouvert, vous pourrez demander un num\u00e9ro d\u2019assurance\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS) - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Si Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) approuve votre demande de permis de travail ouvert, vous pourrez demander un num\u00e9ro d\u2019assurance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-01T15:23:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-demandez-un-numero-dassurance-sociale-nas\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-demandez-un-numero-dassurance-sociale-nas\\\/\",\"name\":\"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS) - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2019-08-08T20:07:01+00:00\",\"dateModified\":\"2021-10-01T15:23:52+00:00\",\"description\":\"Si Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) approuve votre demande de permis de travail ouvert, vous pourrez demander un num\u00e9ro d\u2019assurance\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-demandez-un-numero-dassurance-sociale-nas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-demandez-un-numero-dassurance-sociale-nas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-demandez-un-numero-dassurance-sociale-nas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS) - Justice pas-\u00e0-pas","description":"Si Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) approuve votre demande de permis de travail ouvert, vous pourrez demander un num\u00e9ro d\u2019assurance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/","og_locale":"fr_FR","og_type":"article","og_title":"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS) - Justice pas-\u00e0-pas","og_description":"Si Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) approuve votre demande de permis de travail ouvert, vous pourrez demander un num\u00e9ro d\u2019assurance","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2021-10-01T15:23:52+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/","name":"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS) - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2019-08-08T20:07:01+00:00","dateModified":"2021-10-01T15:23:52+00:00","description":"Si Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) approuve votre demande de permis de travail ouvert, vous pourrez demander un num\u00e9ro d\u2019assurance","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-demandez-un-numero-dassurance-sociale-nas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"4. Demandez un num\u00e9ro d\u2019assurance sociale (NAS)"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171193]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":3,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175571\/revisions"}],"predecessor-version":[{"id":1221573,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175571\/revisions\/1221573"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1175571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}