{"id":1175782,"date":"2020-03-26T14:48:53","date_gmt":"2020-03-26T18:48:53","guid":{"rendered":""},"modified":"2026-04-16T10:12:23","modified_gmt":"2026-04-16T14:12:23","slug":"4-obtenez-une-copie-de-la-mesure-de-renvoi","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/","title":{"rendered":"4. Obtenez une copie de la mesure de renvoi"},"content":{"rendered":"<p>C\u2019est l\u2019Agence des services frontaliers du Canada (ASFC) qui s\u2019occupe d\u2019expulser les gens du Canada. Si l\u2019ASFC tente de vous renvoyer apr\u00e8s une d\u00e9cision de perte d\u2019asile, elle vous rencontrera pour\u00a0:<\/p>\n<ul>\n<li>vous ordonner de quitter le Canada;<\/li>\n<li>confirmer que vous avez perdu le statut de r\u00e9sident permanent (si vous l\u2019aviez).<\/li>\n<\/ul>\n<p>Apr\u00e8s avoir perdu l\u2019asile, vous ne pouvez pas faire une nouvelle demande d\u2019asile au Canada. Et vous n\u2019avez plus le droit de rester au Canada.<\/p>\n<p>Vous pouvez perdre votre statut m\u00eame si vous habitez au Canada depuis longtemps.<\/p>\n<h4>Demandez des conseils juridiques sur vos options<\/h4>\n<p>Selon votre situation, vous pourrez peut-\u00eatre demander\u00a0:<\/p>\n<ul>\n<li>un <a href=\"\/fr\/questions\/refugee-law\/quest-ce-quun-examen-des-risques-avant-renvoi-et-puis-je-en-demander-un\/\">examen des risques avant renvoi<\/a> (ERAR), o\u00f9 vous expliquerez pourquoi vous craignez toujours de retourner dans votre pays;<\/li>\n<li>la r\u00e9sidence permanente pour <a href=\"\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-residence-permanente\/\">consid\u00e9rations d\u2019ordre humanitaire<\/a>;<\/li>\n<li>un sursis \u00e0 l\u2019ex\u00e9cution de la mesure de renvoi, c\u2019est-\u00e0-dire que vous demandez d\u2019avoir plus de temps avant de devoir quitter le pays.<\/li>\n<\/ul>\n<p>Il est tr\u00e8s important d\u2019obtenir de l\u2019assistance juridique concernant ces options. Il y a des r\u00e8gles complexes qui d\u00e9terminent qui peut faire une telle demande et \u00e0 quel moment. Pour l\u2019une ou l\u2019autre de ces trois demandes, il est tr\u00e8s difficile d\u2019obtenir une r\u00e9ponse positive sans l\u2019aide d\u2019un avocat ou d\u2019un autre <a href=\"\/fr\/steps\/refugee-law\/obtenez-de-lassistance-juridique\/\">repr\u00e9sentant autoris\u00e9<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1175782","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>4. Obtenez une copie de la mesure de renvoi - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"C\u2019est l\u2019Agence des services frontaliers du Canada (ASFC) qui s\u2019occupe d\u2019expulser les gens du Canada. Si l\u2019ASFC tente de vous renvoyer apr\u00e8s une d\u00e9cision\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4. Obtenez une copie de la mesure de renvoi - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"C\u2019est l\u2019Agence des services frontaliers du Canada (ASFC) qui s\u2019occupe d\u2019expulser les gens du Canada. Si l\u2019ASFC tente de vous renvoyer apr\u00e8s une d\u00e9cision\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T14:12:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-obtenez-une-copie-de-la-mesure-de-renvoi\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-obtenez-une-copie-de-la-mesure-de-renvoi\\\/\",\"name\":\"4. Obtenez une copie de la mesure de renvoi - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2020-03-26T18:48:53+00:00\",\"dateModified\":\"2026-04-16T14:12:23+00:00\",\"description\":\"C\u2019est l\u2019Agence des services frontaliers du Canada (ASFC) qui s\u2019occupe d\u2019expulser les gens du Canada. Si l\u2019ASFC tente de vous renvoyer apr\u00e8s une d\u00e9cision\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-obtenez-une-copie-de-la-mesure-de-renvoi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-obtenez-une-copie-de-la-mesure-de-renvoi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/refugee-law\\\/4-obtenez-une-copie-de-la-mesure-de-renvoi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4. Obtenez une copie de la mesure de renvoi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4. Obtenez une copie de la mesure de renvoi - Justice pas-\u00e0-pas","description":"C\u2019est l\u2019Agence des services frontaliers du Canada (ASFC) qui s\u2019occupe d\u2019expulser les gens du Canada. Si l\u2019ASFC tente de vous renvoyer apr\u00e8s une d\u00e9cision","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/","og_locale":"fr_FR","og_type":"article","og_title":"4. Obtenez une copie de la mesure de renvoi - Justice pas-\u00e0-pas","og_description":"C\u2019est l\u2019Agence des services frontaliers du Canada (ASFC) qui s\u2019occupe d\u2019expulser les gens du Canada. Si l\u2019ASFC tente de vous renvoyer apr\u00e8s une d\u00e9cision","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2026-04-16T14:12:23+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/","name":"4. Obtenez une copie de la mesure de renvoi - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2020-03-26T18:48:53+00:00","dateModified":"2026-04-16T14:12:23+00:00","description":"C\u2019est l\u2019Agence des services frontaliers du Canada (ASFC) qui s\u2019occupe d\u2019expulser les gens du Canada. Si l\u2019ASFC tente de vous renvoyer apr\u00e8s une d\u00e9cision","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/refugee-law\/4-obtenez-une-copie-de-la-mesure-de-renvoi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"4. Obtenez une copie de la mesure de renvoi"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171342]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":4,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175782\/revisions"}],"predecessor-version":[{"id":1278499,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175782\/revisions\/1278499"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1175782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}