{"id":1175925,"date":"2020-02-18T14:36:42","date_gmt":"2020-02-18T19:36:42","guid":{"rendered":""},"modified":"2025-07-17T13:43:21","modified_gmt":"2025-07-17T17:43:21","slug":"4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/","title":{"rendered":"4.\u00a0Savoir ce qui se passera si vous avez plus d&#8217;un enfant"},"content":{"rendered":"<p>Si vous \u00eates l\u00e9galement mari\u00e9, avez 2 ou plusieurs enfants et d\u00e9c\u00e9dez sans laisser de testament, votre partenaire obtient une <strong>part pr\u00e9f\u00e9rentielle<\/strong> de votre succession.<\/p>\n<p>Cela signifie, en Ontario, qu&#8217;apr\u00e8s le paiement des frais fun\u00e9raires, de l&#8217;imp\u00f4t et des dettes, votre partenaire re\u00e7oit les premiers <strong>350\u00a0000\u00a0$<\/strong> de votre succession.<\/p>\n<p>Donc si votre succession vaut 350\u00a0000\u00a0$ ou moins, tout lui reviendra.<\/p>\n<p>Mais si sa valeur est sup\u00e9rieure \u00e0 350\u00a0000\u00a0$, les premiers 350\u00a0000\u00a0$ lui reviendront. Ensuite, il recevra un tiers de ce qui reste, et les deux autres tiers seront divis\u00e9s \u00e9galement entre vos enfants.<\/p>\n<div class=\"box\">Le 1<sup>er<\/sup>\u00a0mars\u00a02021, le montant de la part pr\u00e9f\u00e9rentielle est pass\u00e9 de 200\u00a0000 \u00e0 350\u00a0000\u00a0$. Pour les personnes d\u00e9c\u00e9d\u00e9es sans testament avant cette date, ce montant \u00e9tait de 200\u00a0000\u00a0$.<\/div>\n<p>Si vous \u00eates s\u00e9par\u00e9 de votre \u00e9poux et d\u00e9c\u00e9dez sans laisser de testament, d&#8217;autres r\u00e8gles s&#8217;appliquent (voir <a href=\"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/1-savoir-ce-qui-se-passera-si-vous-etiez-marie-mais-separe\/\">l&#8217;\u00e9tape\u00a01<\/a>).<\/p>\n<h3>Exemple<\/h3>\n<p>Disons que vous \u00eates mari\u00e9 et avez 4\u00a0enfants. Votre succession vaut 500\u00a0000\u00a0$ apr\u00e8s le paiement des dettes, de l&#8217;imp\u00f4t, des d\u00e9penses et des frais fun\u00e9raires. Votre partenaire recevra la part pr\u00e9f\u00e9rentielle de 350\u00a0000\u00a0$.<\/p>\n<p>Il reste donc 150\u00a0000\u00a0$. Votre partenaire recevra un tiers de ce qui reste, soit 50\u00a0000\u00a0$. Il obtient ainsi au total 400\u00a0000\u00a0$.<\/p>\n<p>Il reste alors 100\u00a0000\u00a0$ que vos enfants se partageront \u00e0 parts \u00e9gales. Chaque enfant recevra donc <strong>25\u00a0000\u00a0$<\/strong>.<\/p>\n<table style=\"width: 100%; height: 609px;\">\n<thead>\n<tr style=\"height: 68px;\">\n<td style=\"height: 68px;\" width=\"204\"><strong>Valeur de la succession<\/strong><\/td>\n<td style=\"height: 68px;\" width=\"227\"><strong>\u00a0 500\u00a0000\u00a0$<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"height: 68px;\">\n<td style=\"height: 68px;\" width=\"204\">Moins la part pr\u00e9f\u00e9rentielle du partenaire<\/td>\n<td style=\"height: 68px;\" width=\"227\">&#8211; 350\u00a0000\u00a0$<\/td>\n<\/tr>\n<tr style=\"height: 68px;\">\n<td style=\"height: 68px;\" width=\"204\">Ce qui reste<\/td>\n<td style=\"height: 68px;\" width=\"227\">= 150\u00a0000\u00a0$<\/td>\n<\/tr>\n<tr style=\"height: 169px;\">\n<td style=\"height: 169px;\" width=\"204\">Montant total re\u00e7u par le partenaire<\/td>\n<td style=\"height: 169px;\" width=\"227\">\u00a0 350\u00a0000\u00a0$ (part pr\u00e9f\u00e9rentielle)\n<p>+ 50\u00a0000\u00a0$ (un tiers de ce qui reste)<\/p>\n<p>= <strong>400\u00a0000\u00a0$<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 118px;\">\n<td style=\"height: 118px;\" width=\"204\">Ce qui reste<\/td>\n<td style=\"height: 118px;\" width=\"227\">\u00a0 500\u00a0000\u00a0$ &#8211; 400\u00a0000\u00a0$\n<p>= 100\u00a0000\u00a0$<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 118px;\">\n<td style=\"height: 118px;\" width=\"204\">Montant re\u00e7u par chacun des 4\u00a0enfants<\/td>\n<td style=\"height: 118px;\" width=\"227\">\u00a0 100\u00a0000\u00a0$ \u00f7 4\n<p>= <strong>25\u00a0000\u00a0$<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Si l&#8217;un de vos enfants meurt avant vous<\/h3>\n<p>Si l&#8217;un de vos enfants meurt avant vous, sa part sera divis\u00e9e \u00e9galement entre ses enfants \u00e0 lui.<\/p>\n<p>S&#8217;il n&#8217;en a pas, sa part ira \u00e0 vos autres enfants vivants.<\/p>\n<h3>Paiement d&#8217;\u00e9galisation<\/h3>\n<p>Votre \u00e9poux peut d\u00e9cider d&#8217;accepter les biens auxquels il a droit\u00a0:<\/p>\n<ul>\n<li>selon les r\u00e8gles de succession sans testament, ou<\/li>\n<li>sous forme de paiement d&#8217;\u00e9galisation en droit de la famille.<\/li>\n<\/ul>\n<p>La question \u00ab\u00a0<a href=\"\/fr\/questions\/family-law\/nous-sommes-maries-si-mon-conjoint-decede-quarrivera-t-il-a-ses-biens\/\">Nous sommes mari\u00e9s. Si mon conjoint d\u00e9c\u00e8de, qu&#8217;arrivera-t-il \u00e0 ses biens?<\/a>\u00a0\u00bb explique ce qu&#8217;est un paiement d&#8217;\u00e9galisation, la fa\u00e7on de le calculer et la date limite pour le demander.<\/p>\n<h3>B\u00e9n\u00e9ficiaires d\u00e9sign\u00e9s<\/h3>\n<p>Les r\u00e8gles sur les <a href=\"https:\/\/stepstojustice.ca\/fr\/questions\/wills-and-powers-of-attorney\/je-suis-marie-quarrivera-t-il-si-je-meurs-sans-laisser-de\/\">b\u00e9n\u00e9ficiaires d\u00e9sign\u00e9s<\/a> continuent de s&#8217;appliquer.<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1175925","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>4.\u00a0Savoir ce qui se passera si vous avez plus d&#039;un enfant - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Si vous \u00eates l\u00e9galement mari\u00e9, avez 2 ou plusieurs enfants et d\u00e9c\u00e9dez sans laisser de testament, votre partenaire obtient une part pr\u00e9f\u00e9rentielle de votre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4.\u00a0Savoir ce qui se passera si vous avez plus d&#039;un enfant - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Si vous \u00eates l\u00e9galement mari\u00e9, avez 2 ou plusieurs enfants et d\u00e9c\u00e9dez sans laisser de testament, votre partenaire obtient une part pr\u00e9f\u00e9rentielle de votre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T17:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/wills-and-powers-of-attorney\\\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/wills-and-powers-of-attorney\\\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\\\/\",\"name\":\"4.\u00a0Savoir ce qui se passera si vous avez plus d'un enfant - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2020-02-18T19:36:42+00:00\",\"dateModified\":\"2025-07-17T17:43:21+00:00\",\"description\":\"Si vous \u00eates l\u00e9galement mari\u00e9, avez 2 ou plusieurs enfants et d\u00e9c\u00e9dez sans laisser de testament, votre partenaire obtient une part pr\u00e9f\u00e9rentielle de votre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/wills-and-powers-of-attorney\\\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/wills-and-powers-of-attorney\\\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/wills-and-powers-of-attorney\\\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4.\u00a0Savoir ce qui se passera si vous avez plus d&#8217;un enfant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4.\u00a0Savoir ce qui se passera si vous avez plus d'un enfant - Justice pas-\u00e0-pas","description":"Si vous \u00eates l\u00e9galement mari\u00e9, avez 2 ou plusieurs enfants et d\u00e9c\u00e9dez sans laisser de testament, votre partenaire obtient une part pr\u00e9f\u00e9rentielle de votre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/","og_locale":"fr_FR","og_type":"article","og_title":"4.\u00a0Savoir ce qui se passera si vous avez plus d'un enfant - Justice pas-\u00e0-pas","og_description":"Si vous \u00eates l\u00e9galement mari\u00e9, avez 2 ou plusieurs enfants et d\u00e9c\u00e9dez sans laisser de testament, votre partenaire obtient une part pr\u00e9f\u00e9rentielle de votre","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2025-07-17T17:43:21+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/","name":"4.\u00a0Savoir ce qui se passera si vous avez plus d'un enfant - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2020-02-18T19:36:42+00:00","dateModified":"2025-07-17T17:43:21+00:00","description":"Si vous \u00eates l\u00e9galement mari\u00e9, avez 2 ou plusieurs enfants et d\u00e9c\u00e9dez sans laisser de testament, votre partenaire obtient une part pr\u00e9f\u00e9rentielle de votre","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/wills-and-powers-of-attorney\/4-savoir-ce-qui-se-passera-si-vous-avez-plus-dun-enfant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"4.\u00a0Savoir ce qui se passera si vous avez plus d&#8217;un enfant"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171155]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":4,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175925\/revisions"}],"predecessor-version":[{"id":1271891,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1175925\/revisions\/1271891"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1175925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}