{"id":1176281,"date":"2018-02-27T14:40:52","date_gmt":"2018-02-27T19:40:52","guid":{"rendered":""},"modified":"2021-08-23T15:46:36","modified_gmt":"2021-08-23T19:46:36","slug":"1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/","title":{"rendered":"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb"},"content":{"rendered":"<p>Votre partenaire et vous-m\u00eame \u00eates des conjoints si vous \u00eates mari\u00e9s ou vivez en union de fait.<\/p>\n<p>Pour les pensions alimentaires du conjoint, vivre en union de fait signifie que\u00a0:<\/p>\n<ul>\n<li>vous avez cohabit\u00e9 en tant que couple pendant au moins trois ans;<\/li>\n<li><strong>ou <\/strong>vous avez v\u00e9cu ensemble dans une relation \u00ab\u00a0d&#8217;une certaine permanence\u00a0\u00bb, peu importe sa dur\u00e9e, et avez eu un enfant ensemble.<\/li>\n<\/ul>\n<p>Cohabiter veut dire que vous habitez ensemble dans une relation semblable \u00e0 un mariage, sans toutefois \u00eatre mari\u00e9s. On parle souvent de \u00ab\u00a0cohabitation\u00a0\u00bb ou d&#8217;\u00ab\u00a0union de fait\u00a0\u00bb.<\/p>\n<p>Le tribunal s&#8217;int\u00e9resse aux questions suivantes pour d\u00e9terminer si vous vivez en union de fait\u00a0:<\/p>\n<ul>\n<li>Habitiez-vous ensemble?<\/li>\n<li>Aviez-vous des relations sexuelles?<\/li>\n<li>Faisiez-vous des t\u00e2ches m\u00e9nag\u00e8res l&#8217;un pour l&#8217;autre, comme la cuisine, le m\u00e9nage et la lessive?<\/li>\n<li>Vous comportiez-vous comme un couple en public?<\/li>\n<li>Vos amis, votre famille et vos proches vous consid\u00e9raient-ils comme un couple?<\/li>\n<li>L&#8217;un des partenaires subvenait-il aux besoins de l&#8217;autre?<\/li>\n<li>Mettiez-vous vos finances en commun?<\/li>\n<li>Avez-vous des enfants ensemble, ou agissiez-vous chacun comme le parent des enfants de l&#8217;autre conjoint?<\/li>\n<\/ul>\n<p>M\u00eame si votre partenaire et vous-m\u00eame n&#8217;avez pas v\u00e9cu ensemble pendant trois ans, vous pourriez quand m\u00eame \u00eatre consid\u00e9r\u00e9s comme des conjoints si vous avez eu un enfant et v\u00e9cu ensemble dans une relation \u00ab\u00a0d&#8217;une certaine permanence\u00a0\u00bb.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1176281","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Votre partenaire et vous-m\u00eame \u00eates des conjoints si vous \u00eates mari\u00e9s ou vivez en union de fait. Pour les pensions alimentaires du conjoint, vivre en union\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Votre partenaire et vous-m\u00eame \u00eates des conjoints si vous \u00eates mari\u00e9s ou vivez en union de fait. Pour les pensions alimentaires du conjoint, vivre en union\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-23T19:46:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\\\/\",\"name\":\"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2018-02-27T19:40:52+00:00\",\"dateModified\":\"2021-08-23T19:46:36+00:00\",\"description\":\"Votre partenaire et vous-m\u00eame \u00eates des conjoints si vous \u00eates mari\u00e9s ou vivez en union de fait. Pour les pensions alimentaires du conjoint, vivre en union\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb - Justice pas-\u00e0-pas","description":"Votre partenaire et vous-m\u00eame \u00eates des conjoints si vous \u00eates mari\u00e9s ou vivez en union de fait. Pour les pensions alimentaires du conjoint, vivre en union","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/","og_locale":"fr_FR","og_type":"article","og_title":"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb - Justice pas-\u00e0-pas","og_description":"Votre partenaire et vous-m\u00eame \u00eates des conjoints si vous \u00eates mari\u00e9s ou vivez en union de fait. Pour les pensions alimentaires du conjoint, vivre en union","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2021-08-23T19:46:36+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/","name":"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2018-02-27T19:40:52+00:00","dateModified":"2021-08-23T19:46:36+00:00","description":"Votre partenaire et vous-m\u00eame \u00eates des conjoints si vous \u00eates mari\u00e9s ou vivez en union de fait. Pour les pensions alimentaires du conjoint, vivre en union","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-repondez-a-la-definition-de-conjoint-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"1. D\u00e9terminez si vous r\u00e9pondez \u00e0 la d\u00e9finition de \u00ab conjoint \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171476]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176281\/revisions"}],"predecessor-version":[{"id":1216442,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176281\/revisions\/1216442"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1176281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}