{"id":1176380,"date":"2018-03-01T10:56:01","date_gmt":"2018-03-01T15:56:01","guid":{"rendered":""},"modified":"2022-02-14T14:59:54","modified_gmt":"2022-02-14T19:59:54","slug":"1-determinez-si-vous-pouvez-obtenir-une-annulation","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/","title":{"rendered":"1. D\u00e9terminez si vous pouvez obtenir une annulation"},"content":{"rendered":"<p>La plupart des couples mari\u00e9s ne peuvent pas obtenir d&#8217;annulation. Ce type d&#8217;ordonnance n&#8217;est rendue que dans quelques situations tr\u00e8s pr\u00e9cises.<\/p>\n<h3>Motifs donnant droit \u00e0 une annulation<\/h3>\n<p>Pour obtenir une annulation, vous devez prouver que votre situation correspond \u00e0 un des sc\u00e9narios suivants.<\/p>\n<h4>Impossibilit\u00e9 pour les partenaires de se marier<\/h4>\n<p>Vous pouvez obtenir une annulation si vous ou votre conjoint ne pouviez pas <a href=\"\/fr\/questions\/family-law\/comment-se-marie-t-en-ontario\/\">vous marier<\/a> pour l&#8217;une des raisons suivantes\u00a0:<\/p>\n<ul>\n<li>l&#8217;un de vous deux \u00e9tait d\u00e9j\u00e0 mari\u00e9, mais l&#8217;autre ne le savait pas;<\/li>\n<li>l&#8217;un de vous deux avait moins de 16\u00a0ans, ou avait 16 ou 17\u00a0ans mais n&#8217;avait pas le consentement de ses parents;<\/li>\n<li>vous avez un lien de parent\u00e9 tr\u00e8s proche, par le sang ou l&#8217;adoption \u2013 pour savoir quels membres d&#8217;une m\u00eame famille ne peuvent pas se marier, consultez l&#8217;\u00e9tape\u00a01 de la section \u00ab\u00a0<a href=\"\/fr\/questions\/family-law\/comment-se-marie-t-en-ontario\/\">Comment se marie-t-on en Ontario?<\/a>\u00a0\u00bb;<\/li>\n<li>l&#8217;un de vous deux ne comprenait pas bien ce que signifiait le mariage \u2013 pour en savoir plus, consultez l&#8217;\u00e9tape\u00a01 de la section \u00ab\u00a0<a href=\"\/fr\/questions\/family-law\/comment-se-marie-t-en-ontario\/\">Comment se marie-t-on en Ontario?<\/a>\u00a0\u00bb;<\/li>\n<li>l&#8217;un de vous deux a \u00e9t\u00e9 forc\u00e9, par l&#8217;autre ou par un tiers, de se marier \u00e0 l&#8217;autre contre sa volont\u00e9.<\/li>\n<\/ul>\n<h4>Probl\u00e8me avec la c\u00e9l\u00e9bration du mariage<\/h4>\n<p>Vous pouvez obtenir une annulation si votre mariage n&#8217;a pas \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9 dans les r\u00e8gles de l&#8217;art.<\/p>\n<p>Par exemple, vous pouvez obtenir une annulation si le c\u00e9l\u00e9brant n&#8217;\u00e9tait pas <a href=\"\/fr\/questions\/family-law\/comment-se-marie-t-en-ontario\/\" rel=\"noopener\">l\u00e9galement autoris\u00e9 \u00e0 vous marier<\/a>.<\/p>\n<h4>Impossibilit\u00e9 d&#8217;avoir des relations sexuelles<\/h4>\n<p>Vous pouvez obtenir une annulation si votre mariage n&#8217;a pas pu \u00eatre consomm\u00e9, c&#8217;est-\u00e0-dire si vous et votre conjoint ne pouvez pas avoir de relations sexuelles en raison d&#8217;une incapacit\u00e9 physique ou mentale inconnue au moment du mariage. Votre mariage ne peut \u00eatre annul\u00e9 si vous et votre conjoint choisissez d\u00e9lib\u00e9r\u00e9ment de ne pas avoir de relations sexuelles.<\/p>\n<h3>Motifs ne donnant pas droit \u00e0 une annulation<\/h3>\n<p>L&#8217;intention des partenaires n&#8217;importe pas. Par exemple, cela n&#8217;a aucune importance si votre conjoint vous a \u00e9pous\u00e9 uniquement pour immigrer au Canada. Aucun tribunal de l&#8217;Ontario ne vous accordera une annulation pour ce motif.<\/p>\n<p>Vous ne pourrez pas non plus obtenir une annulation simplement parce que votre mariage a \u00e9t\u00e9 bref, m\u00eame s&#8217;il n&#8217;a dur\u00e9 que quelques jours.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1176380","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1. D\u00e9terminez si vous pouvez obtenir une annulation - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"La plupart des couples mari\u00e9s ne peuvent pas obtenir d&#039;annulation. Ce type d&#039;ordonnance n&#039;est rendue que dans quelques situations tr\u00e8s pr\u00e9cises. Motifs\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1. D\u00e9terminez si vous pouvez obtenir une annulation - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"La plupart des couples mari\u00e9s ne peuvent pas obtenir d&#039;annulation. Ce type d&#039;ordonnance n&#039;est rendue que dans quelques situations tr\u00e8s pr\u00e9cises. Motifs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-14T19:59:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-pouvez-obtenir-une-annulation\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-pouvez-obtenir-une-annulation\\\/\",\"name\":\"1. D\u00e9terminez si vous pouvez obtenir une annulation - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2018-03-01T15:56:01+00:00\",\"dateModified\":\"2022-02-14T19:59:54+00:00\",\"description\":\"La plupart des couples mari\u00e9s ne peuvent pas obtenir d'annulation. Ce type d'ordonnance n'est rendue que dans quelques situations tr\u00e8s pr\u00e9cises. Motifs\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-pouvez-obtenir-une-annulation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-pouvez-obtenir-une-annulation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/family-law\\\/1-determinez-si-vous-pouvez-obtenir-une-annulation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1. D\u00e9terminez si vous pouvez obtenir une annulation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1. D\u00e9terminez si vous pouvez obtenir une annulation - Justice pas-\u00e0-pas","description":"La plupart des couples mari\u00e9s ne peuvent pas obtenir d'annulation. Ce type d'ordonnance n'est rendue que dans quelques situations tr\u00e8s pr\u00e9cises. Motifs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/","og_locale":"fr_FR","og_type":"article","og_title":"1. D\u00e9terminez si vous pouvez obtenir une annulation - Justice pas-\u00e0-pas","og_description":"La plupart des couples mari\u00e9s ne peuvent pas obtenir d'annulation. Ce type d'ordonnance n'est rendue que dans quelques situations tr\u00e8s pr\u00e9cises. Motifs","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2022-02-14T19:59:54+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/","name":"1. D\u00e9terminez si vous pouvez obtenir une annulation - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2018-03-01T15:56:01+00:00","dateModified":"2022-02-14T19:59:54+00:00","description":"La plupart des couples mari\u00e9s ne peuvent pas obtenir d'annulation. Ce type d'ordonnance n'est rendue que dans quelques situations tr\u00e8s pr\u00e9cises. Motifs","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/family-law\/1-determinez-si-vous-pouvez-obtenir-une-annulation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"1. D\u00e9terminez si vous pouvez obtenir une annulation"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171844]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":2,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176380\/revisions"}],"predecessor-version":[{"id":1233827,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176380\/revisions\/1233827"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1176380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}