{"id":1176775,"date":"2018-05-04T13:46:08","date_gmt":"2018-05-04T17:46:08","guid":{"rendered":""},"modified":"2018-07-30T12:50:04","modified_gmt":"2018-07-30T12:50:04","slug":"1-rassemblez-vos-documents-\u00e0-lappui-0","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/","title":{"rendered":"1. Rassemblez vos documents \u00e0 l&#8217;appui"},"content":{"rendered":"<p>Vous devez prouver qu&#8217;il y a eu un <strong>changement important dans les circonstances, <\/strong>c&#8217;est-\u00e0-dire un changement important dans votre vie qui a un effet sur votre plan de mise en libert\u00e9 sous caution. Par exemple&nbsp;:<\/p>\n<ul>\n<li>votre situation de travail ou vos conditions de vie ont chang\u00e9;<\/li>\n<li>une nouvelle personne a accept\u00e9 de vous cautionner;<\/li>\n<li>des accusations en instance contre vous ont \u00e9t\u00e9 r\u00e9gl\u00e9es.<\/li>\n<\/ul>\n<p>Vous aurez plus de chance de voir votre demande de r\u00e9vision de cautionnement accept\u00e9e si vous avez des documents qui montrent un changement important dans les circonstances. Par exemple, si des accusations en instance contre vous ont \u00e9t\u00e9 r\u00e9gl\u00e9es, fournissez un document qui montre qu&#8217;elles ne sont plus en vigueur.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1176775","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1. Rassemblez vos documents \u00e0 l&#039;appui - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Vous devez prouver qu&#039;il y a eu un changement important dans les circonstances, c&#039;est-\u00e0-dire un changement important dans votre vie qui a un effet sur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1. Rassemblez vos documents \u00e0 l&#039;appui - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Vous devez prouver qu&#039;il y a eu un changement important dans les circonstances, c&#039;est-\u00e0-dire un changement important dans votre vie qui a un effet sur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-30T12:50:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/\",\"name\":\"1. Rassemblez vos documents \u00e0 l'appui - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"dateModified\":\"2018-07-30T12:50:04+00:00\",\"description\":\"Vous devez prouver qu'il y a eu un changement important dans les circonstances, c'est-\u00e0-dire un changement important dans votre vie qui a un effet sur\",\"breadcrumb\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/steps\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1. Rassemblez vos documents \u00e0 l&#8217;appui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"contentUrl\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CLEOLegalRights\/\",\"https:\/\/x.com\/CLEOLegalRights\",\"https:\/\/www.instagram.com\/communitylegaleducationon\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1. Rassemblez vos documents \u00e0 l'appui - Justice pas-\u00e0-pas","description":"Vous devez prouver qu'il y a eu un changement important dans les circonstances, c'est-\u00e0-dire un changement important dans votre vie qui a un effet sur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/","og_locale":"fr_FR","og_type":"article","og_title":"1. Rassemblez vos documents \u00e0 l'appui - Justice pas-\u00e0-pas","og_description":"Vous devez prouver qu'il y a eu un changement important dans les circonstances, c'est-\u00e0-dire un changement important dans votre vie qui a un effet sur","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2018-07-30T12:50:04+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/","name":"1. Rassemblez vos documents \u00e0 l'appui - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"-0001-11-30T00:00:00+00:00","dateModified":"2018-07-30T12:50:04+00:00","description":"Vous devez prouver qu'il y a eu un changement important dans les circonstances, c'est-\u00e0-dire un changement important dans votre vie qui a un effet sur","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/1-rassemblez-vos-documents-\u00e0-lappui-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"1. Rassemblez vos documents \u00e0 l&#8217;appui"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":["1171912"]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1176775\/revisions"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1176775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}