{"id":1177090,"date":"2017-10-23T12:51:02","date_gmt":"2017-10-23T16:51:02","guid":{"rendered":""},"modified":"2021-10-20T12:44:55","modified_gmt":"2021-10-20T16:44:55","slug":"5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/","title":{"rendered":"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s"},"content":{"rendered":"<p>Si vous avez besoin d\u2019aide ou si vous ne savez pas quoi faire en attendant la r\u00e9ponse \u00e0 votre demande d\u2019indemnisation des travailleurs, vous pouvez communiquer avec une <a href=\"\/fr\/questions\/employment-and-work\/o\u00f9-puis-je-obtenir-de-laide-et-des-conseils-relativement-\u00e0-mes-droits\/\">clinique juridique communautaire<\/a> ou un <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/ontario-network-of-injured-workers-groups-oniwg\/\" target=\"_blank\" rel=\"noopener\">groupe de soutien aux travailleurs bless\u00e9s<\/a> (disponible en anglais seulement) dans votre r\u00e9gion.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1177090","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Si vous avez besoin d\u2019aide ou si vous ne savez pas quoi faire en attendant la r\u00e9ponse \u00e0 votre demande d\u2019indemnisation des travailleurs, vous pouvez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Si vous avez besoin d\u2019aide ou si vous ne savez pas quoi faire en attendant la r\u00e9ponse \u00e0 votre demande d\u2019indemnisation des travailleurs, vous pouvez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-20T16:44:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\\\/\",\"name\":\"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2017-10-23T16:51:02+00:00\",\"dateModified\":\"2021-10-20T16:44:55+00:00\",\"description\":\"Si vous avez besoin d\u2019aide ou si vous ne savez pas quoi faire en attendant la r\u00e9ponse \u00e0 votre demande d\u2019indemnisation des travailleurs, vous pouvez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s - Justice pas-\u00e0-pas","description":"Si vous avez besoin d\u2019aide ou si vous ne savez pas quoi faire en attendant la r\u00e9ponse \u00e0 votre demande d\u2019indemnisation des travailleurs, vous pouvez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/","og_locale":"fr_FR","og_type":"article","og_title":"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s - Justice pas-\u00e0-pas","og_description":"Si vous avez besoin d\u2019aide ou si vous ne savez pas quoi faire en attendant la r\u00e9ponse \u00e0 votre demande d\u2019indemnisation des travailleurs, vous pouvez","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2021-10-20T16:44:55+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/","name":"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2017-10-23T16:51:02+00:00","dateModified":"2021-10-20T16:44:55+00:00","description":"Si vous avez besoin d\u2019aide ou si vous ne savez pas quoi faire en attendant la r\u00e9ponse \u00e0 votre demande d\u2019indemnisation des travailleurs, vous pouvez","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/5-communiquez-avec-une-clinique-juridique-ou-le-groupe-de-soutien-aux-travailleurs-blesses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"5. Communiquez avec une clinique juridique ou le groupe de soutien aux travailleurs bless\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171670]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177090\/revisions"}],"predecessor-version":[{"id":1223935,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177090\/revisions\/1223935"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1177090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}