{"id":1177097,"date":"2017-10-23T13:01:18","date_gmt":"2017-10-23T17:01:18","guid":{"rendered":""},"modified":"2026-07-07T14:43:29","modified_gmt":"2026-07-07T18:43:29","slug":"4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/","title":{"rendered":"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB"},"content":{"rendered":"<h3>Demander des mesures d\u2019adaptation<\/h3>\n<p>Vous pouvez demander \u00e0 votre employeur de prendre des mesures d\u2019<strong>adaptation <\/strong>qui vous aideront \u00e0 retourner travailler.<\/p>\n<p>Ce peut \u00eatre n\u2019importe quoi qui sert \u00e0 \u00e9liminer les obstacles \u00e0 votre retour. Par exemple\u00a0:<\/p>\n<ul>\n<li>des changements \u00e0 votre poste de travail, comme un tabouret pour vous asseoir au besoin;<\/li>\n<li>des aides techniques, comme un logiciel de commande vocale pour votre ordinateur ou des \u00e9couteurs avec microphone pour votre t\u00e9l\u00e9phone;<\/li>\n<li>un horaire variable ou des changements \u00e0 votre horaire;<\/li>\n<li>des changements \u00e0 votre description de poste pour enlever ou ajouter des t\u00e2ches.<\/li>\n<\/ul>\n<p>La WSIB peut ordonner \u00e0 votre employeur de vous aider \u00e0 reprendre le travail. Votre employeur ne peut refuser que s\u2019il peut prouver que les mesures d\u2019adaptation requises lui causeraient ce que la WSIB appelle un pr\u00e9judice injustifi\u00e9.<\/p>\n<p>Si votre employeur compte 20\u00a0employ\u00e9s ou plus et que vous travaillez pour lui depuis plus d\u2019un an, il pourrait \u00eatre oblig\u00e9 de vous offrir un autre poste si les deux conditions suivantes s&#8217;appliquent :<\/p>\n<ul>\n<li>votre m\u00e9decin dit que votre situation ne s\u2019am\u00e9liorera pas;<\/li>\n<li>votre m\u00e9decin ou vos autres sp\u00e9cialistes m\u00e9dicaux disent que vous n\u2019\u00eates pas capable d\u2019accomplir les t\u00e2ches principales de votre ancien poste, m\u00eame avec des mesures d\u2019adaptation.<\/li>\n<\/ul>\n<p>Votre employeur peut vous offrir un poste \u00e0 temps partiel m\u00eame si vous \u00e9tiez un employ\u00e9 \u00e0 temps plein avant votre blessure ou votre accident. Cette situation peut se produire si votre m\u00e9decin ne croit pas que vous pouvez reprendre le travail \u00e0 temps plein ou si la WSIB vous offre une formation pour que vous puissiez travailler \u00e0 temps plein plus tard. La WSIB pourrait vous donner 85 % du revenu que vous perdez en travaillant \u00e0 temps partiel plut\u00f4t qu\u2019\u00e0 temps plein.<\/p>\n<p>Si votre employeur vous offre un autre type de travail, vous devez collaborer avec lui, votre m\u00e9decin et les charg\u00e9s de cas sp\u00e9cialis\u00e9s de la Commission de la s\u00e9curit\u00e9 professionnelle et de l\u2019assurance contre les accidents du travail (WSIB) pour d\u00e9terminer ce qui est le mieux pour vous. Un charg\u00e9 de cas sp\u00e9cialis\u00e9 peut aussi vous aider \u00e0 cr\u00e9er un plan de r\u00e9int\u00e9gration \u00e0 long terme.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1177097","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Demander des mesures d\u2019adaptation Vous pouvez demander \u00e0 votre employeur de prendre des mesures d\u2019adaptation qui vous aideront \u00e0 retourner travailler. Ce\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Demander des mesures d\u2019adaptation Vous pouvez demander \u00e0 votre employeur de prendre des mesures d\u2019adaptation qui vous aideront \u00e0 retourner travailler. Ce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T18:43:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\\\/\",\"name\":\"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2017-10-23T17:01:18+00:00\",\"dateModified\":\"2026-07-07T18:43:29+00:00\",\"description\":\"Demander des mesures d\u2019adaptation Vous pouvez demander \u00e0 votre employeur de prendre des mesures d\u2019adaptation qui vous aideront \u00e0 retourner travailler. Ce\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB - Justice pas-\u00e0-pas","description":"Demander des mesures d\u2019adaptation Vous pouvez demander \u00e0 votre employeur de prendre des mesures d\u2019adaptation qui vous aideront \u00e0 retourner travailler. Ce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/","og_locale":"fr_FR","og_type":"article","og_title":"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB - Justice pas-\u00e0-pas","og_description":"Demander des mesures d\u2019adaptation Vous pouvez demander \u00e0 votre employeur de prendre des mesures d\u2019adaptation qui vous aideront \u00e0 retourner travailler. Ce","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2026-07-07T18:43:29+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/","name":"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2017-10-23T17:01:18+00:00","dateModified":"2026-07-07T18:43:29+00:00","description":"Demander des mesures d\u2019adaptation Vous pouvez demander \u00e0 votre employeur de prendre des mesures d\u2019adaptation qui vous aideront \u00e0 retourner travailler. Ce","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-collaborez-avec-votre-employeur-votre-medecin-et-la-cspaat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"4. Collaborez avec votre employeur, votre m\u00e9decin et la WSIB"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171668]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":3,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177097\/revisions"}],"predecessor-version":[{"id":1280939,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177097\/revisions\/1280939"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1177097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}