{"id":1177102,"date":"2017-10-23T14:02:07","date_gmt":"2017-10-23T18:02:07","guid":{"rendered":""},"modified":"2026-07-07T14:30:57","modified_gmt":"2026-07-07T18:30:57","slug":"4-porter-la-decision-en-appel-au-taspaat","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/","title":{"rendered":"4. Porter la d\u00e9cision en appel au TASPAAT"},"content":{"rendered":"<p>Apr\u00e8s votre audience d&#8217;appel \u00e0 la Commission de la s\u00e9curit\u00e9 professionnelle et de l&#8217;assurance contre les accidents du travail (WSIB), la WSIB vous enverra sa d\u00e9cision dans une lettre. Dans cette lettre, elle est cens\u00e9e vous indiquer si la d\u00e9cision est <strong>sans appel<\/strong>. Si elle ne l&#8217;indique pas, communiquez avec la WSIB et demandez-lui directement.<\/p>\n<p>Si vous n&#8217;\u00eates toujours pas d&#8217;accord avec la d\u00e9cision de la WSIB, vous pouvez la porter en appel au Tribunal d&#8217;appel de la s\u00e9curit\u00e9 professionnelle et de l&#8217;assurance contre les accidents du travail (TASPAAT). Il s&#8217;agit d&#8217;un processus complexe. Vous ferez donc bien de <a href=\"https:\/\/stepstojustice.ca\/legal-topic\/employment-and-work\/injured-work\/\">demander de l&#8217;assistance juridique<\/a>.<\/p>\n<p>Pour commencer votre proc\u00e9dure d&#8217;appel, envoyez au TASPAAT un <a href=\"https:\/\/stepstojustice.ca\/fr\/resource\/avis-dappel-pour-travailleur\/\" target=\"_blank\" rel=\"noopener\">Avis d&#8217;appel pour travailleur<\/a>.<\/p>\n<p>Vous devez le faire au plus tard <strong>6 mois<\/strong> apr\u00e8s la date de la d\u00e9cision de la WSIB. Vous pouvez transmettre votre avis par <a href=\"https:\/\/stepstojustice.ca\/fr\/resource\/depot-electronique-de-formulaires-et-de-documents\/\" target=\"_blank\" rel=\"noopener\">d\u00e9p\u00f4t \u00e9lectronique<\/a> ou par t\u00e9l\u00e9copieur au 416\u00a0326-5164. Vous pouvez aussi l&#8217;envoyer par la poste ou par service de messagerie \u00e0 l&#8217;adresse suivante\u00a0:<\/p>\n<p>Tribunal d&#8217;appel de la s\u00e9curit\u00e9 professionnelle et de l&#8217;assurance contre les accidents du travail<br \/>\n505, avenue University, 5<sup>e\u00a0<\/sup>\u00e9tage<br \/>\nToronto (Ontario) \u00a0M5G 2P2<\/p>\n<h3>Si vous d\u00e9passez la date limite<\/h3>\n<p>Si vous envoyez votre avis d&#8217;appel apr\u00e8s la date limite, vous risquez de perdre votre droit d&#8217;appel. Toutefois, le TASPAAT pourrait quand m\u00eame vous permettre d&#8217;interjeter appel contre la d\u00e9cision de la WSIB.<\/p>\n<p>Si votre avis arrive en retard, le TASPAAT vous r\u00e9pondra par une lettre vous invitant \u00e0 demander une prolongation du d\u00e9lai.<\/p>\n<p>Vous aurez alors <strong>1 mois<\/strong>, \u00e0 compter de la date de cette lettre, pour demander une prolongation. Vous pouvez cependant demander au TASPAAT de vous accorder plus d&#8217;un mois.<\/p>\n<p>Pour demander une prolongation du d\u00e9lai, envoyez au TASPAAT\u00a0:<\/p>\n<ul>\n<li>votre Avis d&#8217;appel pour travailleur d\u00fbment rempli,<\/li>\n<li>une lettre o\u00f9 vous expliquez pourquoi vous n&#8217;avez pas pu d\u00e9poser votre appel \u00e0 temps,<\/li>\n<li>et les documents justifiant votre retard, si vous en avez.<\/li>\n<\/ul>\n<p>Pour en savoir plus sur la d\u00e9marche pour demander une prolongation de d\u00e9lai, lisez la <a href=\"https:\/\/stepstojustice.ca\/fr\/resource\/directive-de-procedure-demandes-de-prorogation\/\" target=\"_blank\" rel=\"noopener\">directive de proc\u00e9dure du TASPAAT \u00e0 ce sujet<\/a>.<\/p>\n<p>Si vous avez rat\u00e9 la date limite, <a href=\"https:\/\/stepstojustice.ca\/legal-topic\/employment-and-work\/injured-work\/\">demandez de l&#8217;assistance juridique<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1177102","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>4. Porter la d\u00e9cision en appel au TASPAAT - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s votre audience d&#039;appel \u00e0 la Commission de la s\u00e9curit\u00e9 professionnelle et de l&#039;assurance contre les accidents du travail (WSIB), la WSIB vous enverra\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4. Porter la d\u00e9cision en appel au TASPAAT - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s votre audience d&#039;appel \u00e0 la Commission de la s\u00e9curit\u00e9 professionnelle et de l&#039;assurance contre les accidents du travail (WSIB), la WSIB vous enverra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T18:30:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-porter-la-decision-en-appel-au-taspaat\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-porter-la-decision-en-appel-au-taspaat\\\/\",\"name\":\"4. Porter la d\u00e9cision en appel au TASPAAT - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2017-10-23T18:02:07+00:00\",\"dateModified\":\"2026-07-07T18:30:57+00:00\",\"description\":\"Apr\u00e8s votre audience d'appel \u00e0 la Commission de la s\u00e9curit\u00e9 professionnelle et de l'assurance contre les accidents du travail (WSIB), la WSIB vous enverra\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-porter-la-decision-en-appel-au-taspaat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-porter-la-decision-en-appel-au-taspaat\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/4-porter-la-decision-en-appel-au-taspaat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4. Porter la d\u00e9cision en appel au TASPAAT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4. Porter la d\u00e9cision en appel au TASPAAT - Justice pas-\u00e0-pas","description":"Apr\u00e8s votre audience d'appel \u00e0 la Commission de la s\u00e9curit\u00e9 professionnelle et de l'assurance contre les accidents du travail (WSIB), la WSIB vous enverra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/","og_locale":"fr_FR","og_type":"article","og_title":"4. Porter la d\u00e9cision en appel au TASPAAT - Justice pas-\u00e0-pas","og_description":"Apr\u00e8s votre audience d'appel \u00e0 la Commission de la s\u00e9curit\u00e9 professionnelle et de l'assurance contre les accidents du travail (WSIB), la WSIB vous enverra","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2026-07-07T18:30:57+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/","name":"4. Porter la d\u00e9cision en appel au TASPAAT - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2017-10-23T18:02:07+00:00","dateModified":"2026-07-07T18:30:57+00:00","description":"Apr\u00e8s votre audience d'appel \u00e0 la Commission de la s\u00e9curit\u00e9 professionnelle et de l'assurance contre les accidents du travail (WSIB), la WSIB vous enverra","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/4-porter-la-decision-en-appel-au-taspaat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"4. Porter la d\u00e9cision en appel au TASPAAT"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171667]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":6,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177102\/revisions"}],"predecessor-version":[{"id":1280923,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177102\/revisions\/1280923"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1177102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}