{"id":1177248,"date":"2017-12-06T14:11:05","date_gmt":"2017-12-06T19:11:05","guid":{"rendered":""},"modified":"2025-03-27T12:58:16","modified_gmt":"2025-03-27T16:58:16","slug":"4-remettez-votre-requete-a-la-commission-4","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/","title":{"rendered":"4. Remettez votre requ\u00eate \u00e0 la CLI"},"content":{"rendered":"<p>Une fois que vous avez rempli votre formulaire de requ\u00eate et votre demande de raccourcissement du d\u00e9lai, vous devez remettre vos formulaires \u00e0 la <span class=\"no-glossary\">Commission de la location immobili\u00e8re (CLI)<\/span>.<\/p>\n<p>Des droits de 53 $ sont exig\u00e9s pour le d\u00e9p\u00f4t d&#8217;une requ\u00eate. Ces droits sont de 48 $ si vous utilisez l&#8217;outil e-document. Toutefois, si vous gagnez un faible revenu ou b\u00e9n\u00e9ficiez de l&#8217;aide sociale, vous pouvez demander \u00e0 la <span class=\"no-glossary\">CLI<\/span> de ne pas vous faire payer ces droits. Vous devez pour cela remplir une Demande de dispense du paiement des droits. Vous pouvez vous faire envoyer cette demande par la <span class=\"no-glossary\">CLI<\/span>, ou <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/cli-d-p-t-et-droits-payer\/\" target=\"_blank\" rel=\"noopener\">la t\u00e9l\u00e9charger<\/a> \u00e0 partir de son site Web.<\/p>\n<p>Il existe diff\u00e9rentes fa\u00e7ons de <span class=\"no-glossary\">d\u00e9poser<\/span> votre requ\u00eate :<\/p>\n<p><strong>En personne : <\/strong>Vous pouvez <span class=\"no-glossary\">d\u00e9poser<\/span> votre requ\u00eate \u00e0 un <a class=\"links-link ext new-link\" href=\"\/fr\/resource\/trouver-un-centre-serviceontario\/\" target=\"_blank\" rel=\"noopener\">centre ServiceOntario<\/a>. Les droits de d\u00e9p\u00f4t peuvent \u00eatre pay\u00e9s en argent comptant, carte de cr\u00e9dit, carte de d\u00e9bit, ch\u00e8que certifi\u00e9 ou mandat (les ch\u00e8ques et les mandats doivent \u00eatre faits \u00e0 l&#8217;ordre du ministre des Finances). La <span class=\"no-glossary\">CLI<\/span> n&#8217;accepte pas les ch\u00e8ques non certifi\u00e9s.<\/p>\n<p><strong>Par la poste :<\/strong> Vous pouvez <span class=\"no-glossary\">d\u00e9poser<\/span> votre demande par <a href=\"\/fr\/resource\/communiquer-avec-la-cli\/\" target=\"_blank\" rel=\"noopener\">la poste<\/a>. Inclure le dossier complet de demande.<\/p>\n<p><strong>Par t\u00e9l\u00e9copieur :<\/strong> Vous pouvez envoyer votre demande par t\u00e9l\u00e9copieur au 1-833-610-2242 ou au 416-326-6455. Vous ne pouvez envoyer des t\u00e9l\u00e9copies que si vous avez une dispense de frais ou si le formulaire est gratuit. La CLI vous demande \u00e9galement de n&#8217;utiliser la t\u00e9l\u00e9copie que pour les demandes <strong>urgentes<\/strong>. Par exemple, vous pouvez utiliser la t\u00e9l\u00e9copie si vous demandez une audience plus rapidement.<\/p>\n<p><strong>En ligne :<\/strong> Vous pouvez utiliser le <a href=\"\/fr\/resource\/portail-de-tribunaux-decisionnels-ontario-2\/\" target=\"_blank\" rel=\"noopener\">portail des Tribunaux de l&#8217;Ontario<\/a>. Pour payer les frais, vous devrez donner \u00e0 la CLI les informations de votre carte de cr\u00e9dit ou de d\u00e9bit. Assurez-vous de voir la confirmation \u00e0 l&#8217;\u00e9cran que la CLI a bien re\u00e7u votre demande.<\/p>\n<ul>\n<li>Remarque : Pour l&#8217;instant, vous ne pouvez pas envoyer de formulaire de demande de prolongation ou de raccourcissement d&#8217;un d\u00e9lai par l&#8217;interm\u00e9diaire du portail des tribunaux de l&#8217;Ontario. Apr\u00e8s avoir d\u00e9pos\u00e9 votre demande dans le portail, envoyez le formulaire par courriel \u00e0 <a href=\"mailto:ltb@ontario.ca\">ltb@ontario.ca<\/a> en indiquant votre num\u00e9ro de dossier dans la ligne d&#8217;objet du courriel.<\/li>\n<\/ul>\n<div class=\"resource-shortcode \"><a class=\"resource-box resource-shortcode bordered document-fr has-image\" href=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/How-to-make-a-Tribunals-Ontario-Portal-account-fr-final.pdf\" target=\"_blank\" data-id= 1269219 data-type=\"resource\"><div class=\"img-box\" ><img src = \"https:\/\/stepstojustice.ca\/wp-content\/uploads\/How-to-make-a-Tribunals-Ontario-Portal-account-fr-final.pdf.png\" alt = \"\" ><\/div ><div class=\"text-box\"><div class=\"title-box\"><p class=\"resource-title\">Comment cr\u00e9er un compte sur le portail Tribunaux d\u00e9cisionnels Ontario<\/p><p class=\"author\">CLEO<\/p><span class=\"icon\"><img decoding=\"async\" class=\"style-svg1189722\" src=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/icon-document.svg\" alt=\"icon-document.svg\"\/><\/span><\/div><p><span data-olk-copy-source=\"MessageBody\">Utilisez cette fiche-conseil pour cr\u00e9er un compte<\/span><\/p>\n<\/div><\/a><\/div>\n<p>N&#8217;oubliez pas d&#8217;envoyer des copies de toute preuve que vous voulez utiliser \u00e0 votre <span class=\"no-glossary\">propri\u00e9taire<\/span> et \u00e0 la CLI au moins <strong>7 jours<\/strong> avant votre audience.<\/p>\n<p>La CLI envoie habituellement l&#8217;<span class=\"no-glossary\">avis<\/span> d&#8217;audience et une copie de votre requ\u00eate \u00e0 votre <span class=\"no-glossary\">propri\u00e9taire<\/span>. La CLI vous dira si vous devez la lui remettre vous-m\u00eame.<\/p>\n<p>Vous devriez commencer \u00e0 <a href=\"\/fr\/questions\/housing-law\/jai-presente-ma-requete-a-la-cli-comment-dois-je-me-preparer-pour-mon-audience\/\">vous pr\u00e9parer pour l&#8217;audience<\/a> le plus rapidement possible. Il est important que vous arriviez bien pr\u00e9par\u00e9. Ce sera votre seule chance de faire valoir vos droits. Si vous arrivez mal pr\u00e9par\u00e9 ou s&#8217;il vous manque des preuves importantes, il est peu probable que la <span class=\"no-glossary\">CLI<\/span> vous accorde une nouvelle audience.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1177248","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4. Remettez votre requ\u00eate \u00e0 la CLI - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Une fois que vous avez rempli votre formulaire de requ\u00eate et votre demande de raccourcissement du d\u00e9lai, vous devez remettre vos formulaires \u00e0 la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4. Remettez votre requ\u00eate \u00e0 la CLI - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Une fois que vous avez rempli votre formulaire de requ\u00eate et votre demande de raccourcissement du d\u00e9lai, vous devez remettre vos formulaires \u00e0 la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T16:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/\",\"name\":\"4. Remettez votre requ\u00eate \u00e0 la CLI - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"2017-12-06T19:11:05+00:00\",\"dateModified\":\"2025-03-27T16:58:16+00:00\",\"description\":\"Une fois que vous avez rempli votre formulaire de requ\u00eate et votre demande de raccourcissement du d\u00e9lai, vous devez remettre vos formulaires \u00e0 la\",\"breadcrumb\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/steps\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4. Remettez votre requ\u00eate \u00e0 la CLI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"contentUrl\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CLEOLegalRights\/\",\"https:\/\/x.com\/CLEOLegalRights\",\"https:\/\/www.instagram.com\/communitylegaleducationon\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4. Remettez votre requ\u00eate \u00e0 la CLI - Justice pas-\u00e0-pas","description":"Une fois que vous avez rempli votre formulaire de requ\u00eate et votre demande de raccourcissement du d\u00e9lai, vous devez remettre vos formulaires \u00e0 la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/","og_locale":"fr_FR","og_type":"article","og_title":"4. Remettez votre requ\u00eate \u00e0 la CLI - Justice pas-\u00e0-pas","og_description":"Une fois que vous avez rempli votre formulaire de requ\u00eate et votre demande de raccourcissement du d\u00e9lai, vous devez remettre vos formulaires \u00e0 la","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2025-03-27T16:58:16+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/","name":"4. Remettez votre requ\u00eate \u00e0 la CLI - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2017-12-06T19:11:05+00:00","dateModified":"2025-03-27T16:58:16+00:00","description":"Une fois que vous avez rempli votre formulaire de requ\u00eate et votre demande de raccourcissement du d\u00e9lai, vous devez remettre vos formulaires \u00e0 la","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/housing-law\/4-remettez-votre-requete-a-la-commission-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"4. Remettez votre requ\u00eate \u00e0 la CLI"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":["1171637"]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":22,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177248\/revisions"}],"predecessor-version":[{"id":1269242,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177248\/revisions\/1269242"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1177248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}