{"id":1177395,"date":"2017-10-18T13:44:21","date_gmt":"2017-10-18T17:44:21","guid":{"rendered":""},"modified":"2024-02-06T16:19:18","modified_gmt":"2024-02-06T21:19:18","slug":"portez-plainte-au-ministere-du-travail","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/","title":{"rendered":"Portez plainte au minist\u00e8re du Travail"},"content":{"rendered":"<p>Si votre employeur ne respecte pas la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario, vous pouvez porter plainte au minist\u00e8re du Travail.<\/p>\n<p>Le Minist\u00e8re pourrait envoyer un inspecteur \u00e0 votre lieu de travail pour \u00e9valuer la situation et d\u00e9terminer si la LSST a \u00e9t\u00e9 viol\u00e9e.<\/p>\n<p>Quand l\u2019inspecteur m\u00e8ne une enqu\u00eate, il amasse de l\u2019information et arrive \u00e0 une d\u00e9cision \u00e0 l&#8217;\u00e9gard de la situation. Il consigne ses conclusions dans un rapport, puis en donne une copie \u00e0 votre employeur et \u00e0 votre repr\u00e9sentant. Votre employeur doit afficher le rapport de l&#8217;inspecteur sur le lieu de travail o\u00f9 les employ\u00e9s peuvent le voir.<\/p>\n<p>L\u2019inspecteur peut ordonner \u00e0 votre employeur de respecter la loi. S\u2019il croit que vous ou d\u2019autres travailleurs \u00eates en danger, il peut aussi\u00a0:<\/p>\n<ul>\n<li>ordonner \u00e0 l\u2019employeur de r\u00e9parer une structure, de l\u2019\u00e9quipement ou un objet;<\/li>\n<li>ordonner qu\u2019un appareil ne soit pas utilis\u00e9 jusqu\u2019\u00e0 ce qu\u2019il soit r\u00e9par\u00e9;<\/li>\n<li>interrompre les activit\u00e9s dans votre lieu de travail jusqu\u2019\u00e0 ce que le probl\u00e8me soit r\u00e9gl\u00e9;<\/li>\n<li>ordonner \u00e0 tous de quitter un endroit dangereux jusqu\u2019\u00e0 ce que le probl\u00e8me soit r\u00e9gl\u00e9.<\/li>\n<\/ul>\n<p>Vous pouvez appeler l\u2019InfoCentre de sant\u00e9 et de s\u00e9curit\u00e9 au travail du minist\u00e8re du Travail au 1\u00a0877\u00a0202\u20110008 pour porter plainte. <span lang=\"FR\">Vous pouvez \u00e9galement d\u00e9poser une plainte <a href=\"\/fr\/resource\/depot-dune-plainte-en-matiere-de-sante-et-securite-au-travail-generalites\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\" data-ogsc=\"\">en ligne<\/a>. <\/span>Vous pouvez le faire n\u2019importe quand; pas besoin de parler d\u2019abord du probl\u00e8me \u00e0 votre superviseur.<\/p>\n<p>Votre employeur n\u2019a pas le droit de <a href=\"\/fr\/questions\/employment-and-work\/mon-employeur-peut-il-me-punir-si-je-porte-plainte-\u00e0-propos\/\" rel=\"noopener\">vous punir pour votre plainte<\/a>. De plus, vous n\u2019avez pas besoin de donner votre nom au minist\u00e8re du Travail pour porter plainte.<\/p>\n<p>Si vous n\u2019\u00eates pas d\u2019accord avec la d\u00e9cision de l\u2019inspecteur, vous pouvez demander \u00e0 la Commission des relations de travail de l\u2019Ontario (CRTO) de la changer. Autrement dit, vous pouvez <a href=\"\/fr\/questions\/employment-and-work\/je-ne-suis-pas-daccord-avec-la-d\u00e9cision-prise-par-linspecteur-du\/\" rel=\"noopener\">faire appel de cette d\u00e9cision<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1177395","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Portez plainte au minist\u00e8re du Travail - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Si votre employeur ne respecte pas la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario, vous pouvez porter plainte au minist\u00e8re du Travail.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portez plainte au minist\u00e8re du Travail - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Si votre employeur ne respecte pas la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario, vous pouvez porter plainte au minist\u00e8re du Travail.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T21:19:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/portez-plainte-au-ministere-du-travail\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/portez-plainte-au-ministere-du-travail\\\/\",\"name\":\"Portez plainte au minist\u00e8re du Travail - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2017-10-18T17:44:21+00:00\",\"dateModified\":\"2024-02-06T21:19:18+00:00\",\"description\":\"Si votre employeur ne respecte pas la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario, vous pouvez porter plainte au minist\u00e8re du Travail.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/portez-plainte-au-ministere-du-travail\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/portez-plainte-au-ministere-du-travail\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/portez-plainte-au-ministere-du-travail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Portez plainte au minist\u00e8re du Travail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Portez plainte au minist\u00e8re du Travail - Justice pas-\u00e0-pas","description":"Si votre employeur ne respecte pas la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario, vous pouvez porter plainte au minist\u00e8re du Travail.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/","og_locale":"fr_FR","og_type":"article","og_title":"Portez plainte au minist\u00e8re du Travail - Justice pas-\u00e0-pas","og_description":"Si votre employeur ne respecte pas la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario, vous pouvez porter plainte au minist\u00e8re du Travail.","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2024-02-06T21:19:18+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/","name":"Portez plainte au minist\u00e8re du Travail - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2017-10-18T17:44:21+00:00","dateModified":"2024-02-06T21:19:18+00:00","description":"Si votre employeur ne respecte pas la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario, vous pouvez porter plainte au minist\u00e8re du Travail.","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/portez-plainte-au-ministere-du-travail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"Portez plainte au minist\u00e8re du Travail"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171619]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":4,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177395\/revisions"}],"predecessor-version":[{"id":1261781,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177395\/revisions\/1261781"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1177395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}