{"id":1177512,"date":"2017-10-23T10:16:41","date_gmt":"2017-10-23T14:16:41","guid":{"rendered":""},"modified":"2021-10-20T10:57:39","modified_gmt":"2021-10-20T14:57:39","slug":"envisager-dappeler-la-police","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/","title":{"rendered":"Envisager d\u2019appeler la police"},"content":{"rendered":"<p>Si vous ou quelqu\u2019un d\u2019autre \u00eates en danger imm\u00e9diat, vous pouvez appeler la police.<\/p>\n<p>Si quelqu\u2019un vous agresse ou vous menace au travail, il commet un crime. Cela n\u2019a pas d\u2019importance s\u2019il s\u2019agit d\u2019un coll\u00e8gue ou d\u2019un membre du public.<\/p>\n<p>La police \u00e9tudie la situation et d\u00e9termine si la personne doit \u00eatre inculp\u00e9e. Si vous avez vu ce qui s\u2019est pass\u00e9, ou si c\u2019est vous qui avez appel\u00e9 la police, celle-ci pourrait vous demander de faire une d\u00e9claration.<\/p>\n<p>Si un travailleur est bless\u00e9 par un acte de violence au travail, votre employeur doit appeler les secours m\u00e9dicaux ou la police sans tarder.<\/p>\n<p>Il pourrait aussi avoir \u00e0 appeler l\u2019<a class=\"links-link ext new-link\" href=\"\/fr\/resource\/infocentre-de-sant-et-de-s-curit-au-travail-du-minist-re-du-travail\/\" target=\"_blank\" rel=\"noopener\">InfoCentre de sant\u00e9 et de s\u00e9curit\u00e9 au travail du minist\u00e8re du Travail<\/a> au 1\u00a0877\u00a0202\u20110008. Le Minist\u00e8re pourrait envoyer un inspecteur \u00e0 votre lieu de travail.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1177512","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Envisager d\u2019appeler la police - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Si vous ou quelqu\u2019un d\u2019autre \u00eates en danger imm\u00e9diat, vous pouvez appeler la police. Si quelqu\u2019un vous agresse ou vous menace au travail, il commet un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Envisager d\u2019appeler la police - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Si vous ou quelqu\u2019un d\u2019autre \u00eates en danger imm\u00e9diat, vous pouvez appeler la police. Si quelqu\u2019un vous agresse ou vous menace au travail, il commet un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-20T14:57:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/envisager-dappeler-la-police\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/envisager-dappeler-la-police\\\/\",\"name\":\"Envisager d\u2019appeler la police - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2017-10-23T14:16:41+00:00\",\"dateModified\":\"2021-10-20T14:57:39+00:00\",\"description\":\"Si vous ou quelqu\u2019un d\u2019autre \u00eates en danger imm\u00e9diat, vous pouvez appeler la police. Si quelqu\u2019un vous agresse ou vous menace au travail, il commet un\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/envisager-dappeler-la-police\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/envisager-dappeler-la-police\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/employment-and-work\\\/envisager-dappeler-la-police\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Envisager d\u2019appeler la police\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Envisager d\u2019appeler la police - Justice pas-\u00e0-pas","description":"Si vous ou quelqu\u2019un d\u2019autre \u00eates en danger imm\u00e9diat, vous pouvez appeler la police. Si quelqu\u2019un vous agresse ou vous menace au travail, il commet un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/","og_locale":"fr_FR","og_type":"article","og_title":"Envisager d\u2019appeler la police - Justice pas-\u00e0-pas","og_description":"Si vous ou quelqu\u2019un d\u2019autre \u00eates en danger imm\u00e9diat, vous pouvez appeler la police. Si quelqu\u2019un vous agresse ou vous menace au travail, il commet un","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2021-10-20T14:57:39+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/","name":"Envisager d\u2019appeler la police - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2017-10-23T14:16:41+00:00","dateModified":"2021-10-20T14:57:39+00:00","description":"Si vous ou quelqu\u2019un d\u2019autre \u00eates en danger imm\u00e9diat, vous pouvez appeler la police. Si quelqu\u2019un vous agresse ou vous menace au travail, il commet un","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/employment-and-work\/envisager-dappeler-la-police\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"Envisager d\u2019appeler la police"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171571]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177512\/revisions"}],"predecessor-version":[{"id":1223886,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177512\/revisions\/1223886"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1177512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}