{"id":1178143,"date":"2018-01-02T14:10:25","date_gmt":"2018-01-02T19:10:25","guid":{"rendered":""},"modified":"2022-03-11T10:07:41","modified_gmt":"2022-03-11T15:07:41","slug":"2-demandez-si-vous-etes-en-etat-darrestation","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/","title":{"rendered":"2. Demandez si vous \u00eates en \u00e9tat d&#8217;arrestation"},"content":{"rendered":"<p>Demandez si vous \u00eates en \u00e9tat d&#8217;arrestation. Si c&#8217;est le cas, vous avez le <strong>droit de savoir pourquoi.<\/strong><\/p>\n<h3>Les pouvoirs de la police<\/h3>\n<p>Lorsqu&#8217;elle vous arr\u00eate, la police peut vous fouiller afin de\u00a0:<\/p>\n<ul>\n<li>trouver des preuves en lien avec l&#8217;infraction pour laquelle elle vous arr\u00eate;<\/li>\n<li>vous emp\u00eacher de d\u00e9truire des preuves;<\/li>\n<li>prot\u00e9ger les policiers ou le public.<\/li>\n<\/ul>\n<p>En cas d&#8217;arrestation, la fouille peut \u00eatre plus compl\u00e8te. La police peut fouiller votre <strong>environnement physique imm\u00e9diat<\/strong>, qui comprend\u00a0:<\/p>\n<ul>\n<li>votre personne;<\/li>\n<li>vos v\u00eatements;<\/li>\n<li>tout ce que vous portez sur vous, dont votre t\u00e9l\u00e9phone cellulaire;<\/li>\n<li>votre v\u00e9hicule, si c&#8217;est l&#8217;endroit o\u00f9 vous avez \u00e9t\u00e9 arr\u00eat\u00e9.<\/li>\n<\/ul>\n<p>Si vous \u00eates arr\u00eat\u00e9 sans mandat, il peut difficile pour les policiers de fouiller votre <strong>t\u00e9l\u00e9phone cellulaire<\/strong> si celui-ci est prot\u00e9g\u00e9 par un mot de passe. Cela ne leur enl\u00e8ve pas le droit de le fouiller, mais comme vous avez le droit de garder le silence, vous pouvez ne pas leur r\u00e9v\u00e9ler votre mot de passe.<\/p>\n<h3>Consultez un avocat<\/h3>\n<p>Si la police vous arr\u00eate, demandez \u00e0 parler imm\u00e9diatement \u00e0 un avocat.<\/p>\n<p>Vous avez le droit de parler \u00e0 un avocat si vous \u00eates arr\u00eat\u00e9. Les policiers ont l&#8217;obligation de vous informer de ce droit. Si vous leur dites que vous voulez consulter un avocat, ils doivent non seulement vous le permettre, mais aussi vous laisser le faire en priv\u00e9.<\/p>\n<p>Les policiers doivent aussi vous informer de l&#8217;existence d&#8217;<a class=\"links-link ext new-link\" href=\"\/fr\/resource\/aide-juridique-ontario-1-1\/\" target=\"_blank\" rel=\"noopener\">Aide juridique Ontario<\/a>. Cet organisme paie des avocats, appel\u00e9s <strong>avocats de service,<\/strong> pour qu&#8217;ils vous donnent un avis juridique gratuitement si vous \u00eates arr\u00eat\u00e9 ou d\u00e9tenu. Ce service est disponible 24\u00a0heures sur 24. En cas d&#8217;arrestation ou de d\u00e9tention, vous pouvez communiquer imm\u00e9diatement avec un avocat de service. Si les policiers ne vous donnent pas le num\u00e9ro sans frais pour en joindre un, demandez-le-leur.<\/p>\n<p>Tous ces droits renvoient \u00e0 ce qu&#8217;on appelle le <strong>droit \u00e0 un avocat.<\/strong> Consultez toujours un avocat avant de parler aux policiers.<\/p>\n<h3>Droit de garder le silence<\/h3>\n<p>Vous avez le <strong>droit de garder le silence.<\/strong> Dans la plupart des cas, vous n&#8217;\u00eates pas oblig\u00e9 de r\u00e9pondre aux questions de la police. D&#8217;ailleurs, tout ce que vous lui direz pourra servir de preuve plus tard.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":3,"featured_media":0,"template":"","class_list":["post-1178143","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>2. Demandez si vous \u00eates en \u00e9tat d&#039;arrestation - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Demandez si vous \u00eates en \u00e9tat d&#039;arrestation. Si c&#039;est le cas, vous avez le droit de savoir pourquoi. Les pouvoirs de la police Lorsqu&#039;elle vous arr\u00eate, la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2. Demandez si vous \u00eates en \u00e9tat d&#039;arrestation - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Demandez si vous \u00eates en \u00e9tat d&#039;arrestation. Si c&#039;est le cas, vous avez le droit de savoir pourquoi. Les pouvoirs de la police Lorsqu&#039;elle vous arr\u00eate, la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-11T15:07:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/criminal-law\\\/2-demandez-si-vous-etes-en-etat-darrestation\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/criminal-law\\\/2-demandez-si-vous-etes-en-etat-darrestation\\\/\",\"name\":\"2. Demandez si vous \u00eates en \u00e9tat d'arrestation - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\"},\"datePublished\":\"2018-01-02T19:10:25+00:00\",\"dateModified\":\"2022-03-11T15:07:41+00:00\",\"description\":\"Demandez si vous \u00eates en \u00e9tat d'arrestation. Si c'est le cas, vous avez le droit de savoir pourquoi. Les pouvoirs de la police Lorsqu'elle vous arr\u00eate, la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/criminal-law\\\/2-demandez-si-vous-etes-en-etat-darrestation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/criminal-law\\\/2-demandez-si-vous-etes-en-etat-darrestation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/criminal-law\\\/2-demandez-si-vous-etes-en-etat-darrestation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/steps\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2. Demandez si vous \u00eates en \u00e9tat d&#8217;arrestation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"contentUrl\":\"https:\\\/\\\/stepstojustice.ca\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\\\/\\\/stepstojustice.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CLEOLegalRights\\\/\",\"https:\\\/\\\/x.com\\\/CLEOLegalRights\",\"https:\\\/\\\/www.instagram.com\\\/communitylegaleducationon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2. Demandez si vous \u00eates en \u00e9tat d'arrestation - Justice pas-\u00e0-pas","description":"Demandez si vous \u00eates en \u00e9tat d'arrestation. Si c'est le cas, vous avez le droit de savoir pourquoi. Les pouvoirs de la police Lorsqu'elle vous arr\u00eate, la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/","og_locale":"fr_FR","og_type":"article","og_title":"2. Demandez si vous \u00eates en \u00e9tat d'arrestation - Justice pas-\u00e0-pas","og_description":"Demandez si vous \u00eates en \u00e9tat d'arrestation. Si c'est le cas, vous avez le droit de savoir pourquoi. Les pouvoirs de la police Lorsqu'elle vous arr\u00eate, la","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2022-03-11T15:07:41+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/","name":"2. Demandez si vous \u00eates en \u00e9tat d'arrestation - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2018-01-02T19:10:25+00:00","dateModified":"2022-03-11T15:07:41+00:00","description":"Demandez si vous \u00eates en \u00e9tat d'arrestation. Si c'est le cas, vous avez le droit de savoir pourquoi. Les pouvoirs de la police Lorsqu'elle vous arr\u00eate, la","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/2-demandez-si-vous-etes-en-etat-darrestation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"2. Demandez si vous \u00eates en \u00e9tat d&#8217;arrestation"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[1171417]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1178143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":2,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1178143\/revisions"}],"predecessor-version":[{"id":1235898,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1178143\/revisions\/1235898"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1178143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}