{"id":1229516,"date":"2021-12-22T10:34:32","date_gmt":"2021-12-22T15:34:32","guid":{"rendered":"https:\/\/stepstojustice.ca\/?post_type=steps&#038;p=1229516"},"modified":"2021-12-22T10:42:23","modified_gmt":"2021-12-22T15:42:23","slug":"demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir","status":"publish","type":"steps","link":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/","title":{"rendered":"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir"},"content":{"rendered":"<p>Il se peut que vous n\u2019arriviez pas \u00e0 obtenir une \u00e9valuation de l\u2019incidence de l\u2019origine ethnique et culturelle (EIOEC) ou un rapport similaire pour votre audience de d\u00e9termination de la peine. Mais vous pouvez demander au juge de tenir compte de votre race et de vos ant\u00e9c\u00e9dents culturels en appliquant la \u00ab\u00a0connaissance d\u2019office\u00a0\u00bb.<\/p>\n<p>Prendre connaissance d\u2019office de quelque chose signifie admettre que cette chose est vraie, m\u00eame sans preuve. Selon la loi, un juge peut le faire seulement si quelque chose est <strong>manifestement vrai<\/strong>.<\/p>\n<h3><strong>Connaissance d\u2019office du racisme anti-Noir<\/strong><\/h3>\n<p><strong>En Ontario, les juges peuvent prendre connaissance d\u2019office du racisme syst\u00e9mique anti-Noir et de ses r\u00e9percussions.<\/strong><\/p>\n<p>Autrement dit, pour d\u00e9terminer votre peine, le juge peut dire\u00a0:<\/p>\n<ul>\n<li>que les personnes noires au Canada sont affect\u00e9es de fa\u00e7on n\u00e9gative par les attitudes racistes affich\u00e9es dans la soci\u00e9t\u00e9, et<\/li>\n<li>que certaines pratiques racistes ont cours dans les \u00e9coles, les lieux de travail, les milieux de soins et les logements, par exemple; c\u2019est ce qu\u2019on appelle le \u00ab\u00a0racisme syst\u00e9mique anti-Noir\u00a0\u00bb.<\/li>\n<\/ul>\n<p>De plus, le juge peut dire qu\u2019en raison de cette forme de racisme, une personne noire est plus \u00e0 risque que les autres d\u2019avoir de mauvaises exp\u00e9riences avec la police et les tribunaux p\u00e9naux.<\/p>\n<p>La connaissance d\u2019office permet au juge de le mentionner lors de la d\u00e9termination de la peine, m\u00eame s\u2019il n\u2019a pas re\u00e7u d\u2019EIOEC ou de rapport similaire. Vous pouvez indiquer au juge que les paragraphes\u00a042 et 123 de l\u2019<a href=\"\/fr\/resource\/r-v-morris-2021-onca-680-canlii\/\" target=\"_blank\" rel=\"noopener\">affaire <em>R.\u00a0c.\u00a0Morris<\/em><\/a> (disponible en anglais seulement) traitent aussi de la connaissance d\u2019office du racisme anti-Noir.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":11,"featured_media":0,"template":"","class_list":["post-1229516","steps","type-steps","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir - Justice pas-\u00e0-pas<\/title>\n<meta name=\"description\" content=\"Il se peut que vous n\u2019arriviez pas \u00e0 obtenir une \u00e9valuation de l\u2019incidence de l\u2019origine ethnique et culturelle (EIOEC) ou un rapport similaire pour votre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir - Justice pas-\u00e0-pas\" \/>\n<meta property=\"og:description\" content=\"Il se peut que vous n\u2019arriviez pas \u00e0 obtenir une \u00e9valuation de l\u2019incidence de l\u2019origine ethnique et culturelle (EIOEC) ou un rapport similaire pour votre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/\" \/>\n<meta property=\"og:site_name\" content=\"Justice pas-\u00e0-pas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLEOLegalRights\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-22T15:42:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CLEOLegalRights\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/\",\"name\":\"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir - Justice pas-\u00e0-pas\",\"isPartOf\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"2021-12-22T15:34:32+00:00\",\"dateModified\":\"2021-12-22T15:42:23+00:00\",\"description\":\"Il se peut que vous n\u2019arriviez pas \u00e0 obtenir une \u00e9valuation de l\u2019incidence de l\u2019origine ethnique et culturelle (EIOEC) ou un rapport similaire pour votre\",\"breadcrumb\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\/\/stepstojustice.ca\/fr\/steps\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"name\":\"Justice pas-\u00e0-pas\",\"description\":\"Step-by-step information about legal problems\",\"publisher\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#organization\",\"name\":\"Justice pas-\u00e0-pas\",\"url\":\"https:\/\/stepstojustice.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"contentUrl\":\"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png\",\"width\":1000,\"height\":146,\"caption\":\"Justice pas-\u00e0-pas\"},\"image\":{\"@id\":\"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CLEOLegalRights\/\",\"https:\/\/x.com\/CLEOLegalRights\",\"https:\/\/www.instagram.com\/communitylegaleducationon\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir - Justice pas-\u00e0-pas","description":"Il se peut que vous n\u2019arriviez pas \u00e0 obtenir une \u00e9valuation de l\u2019incidence de l\u2019origine ethnique et culturelle (EIOEC) ou un rapport similaire pour votre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/","og_locale":"fr_FR","og_type":"article","og_title":"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir - Justice pas-\u00e0-pas","og_description":"Il se peut que vous n\u2019arriviez pas \u00e0 obtenir une \u00e9valuation de l\u2019incidence de l\u2019origine ethnique et culturelle (EIOEC) ou un rapport similaire pour votre","og_url":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/","og_site_name":"Justice pas-\u00e0-pas","article_publisher":"https:\/\/www.facebook.com\/CLEOLegalRights\/","article_modified_time":"2021-12-22T15:42:23+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/Steps-to-Justice-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CLEOLegalRights","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/","url":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/","name":"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir - Justice pas-\u00e0-pas","isPartOf":{"@id":"https:\/\/stepstojustice.ca\/fr\/#website"},"datePublished":"2021-12-22T15:34:32+00:00","dateModified":"2021-12-22T15:42:23+00:00","description":"Il se peut que vous n\u2019arriviez pas \u00e0 obtenir une \u00e9valuation de l\u2019incidence de l\u2019origine ethnique et culturelle (EIOEC) ou un rapport similaire pour votre","breadcrumb":{"@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stepstojustice.ca\/fr\/steps\/criminal-law\/demandez-au-juge-de-prendre-connaissance-doffice-du-racisme-anti-noir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/stepstojustice.ca\/fr\/steps\/"},{"@type":"ListItem","position":3,"name":"2. Demandez au juge de prendre connaissance d\u2019office du racisme anti-Noir"}]},{"@type":"WebSite","@id":"https:\/\/stepstojustice.ca\/fr\/#website","url":"https:\/\/stepstojustice.ca\/fr\/","name":"Justice pas-\u00e0-pas","description":"Step-by-step information about legal problems","publisher":{"@id":"https:\/\/stepstojustice.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stepstojustice.ca\/fr\/#organization","name":"Justice pas-\u00e0-pas","url":"https:\/\/stepstojustice.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","contentUrl":"https:\/\/stepstojustice.ca\/wp-content\/uploads\/2020\/10\/logo-s2j.png","width":1000,"height":146,"caption":"Justice pas-\u00e0-pas"},"image":{"@id":"https:\/\/stepstojustice.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLEOLegalRights\/","https:\/\/x.com\/CLEOLegalRights","https:\/\/www.instagram.com\/communitylegaleducationon\/"]}]}},"meta_box":{"questions_to_steps_from":[]},"_links":{"self":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1229516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":3,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1229516\/revisions"}],"predecessor-version":[{"id":1229530,"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1229516\/revisions\/1229530"}],"wp:attachment":[{"href":"https:\/\/stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1229516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}